{"id":9107,"date":"2021-03-30T08:00:31","date_gmt":"2021-03-30T11:00:31","guid":{"rendered":"https:\/\/nfe.io\/blog\/?p=9107"},"modified":"2025-06-30T07:43:21","modified_gmt":"2025-06-30T10:43:21","slug":"o-que-e-certidao-negativa-de-debitos","status":"publish","type":"post","link":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/","title":{"rendered":"O que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos e a import\u00e2ncia para a empresa"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Voc\u00ea sabe o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos? Trata-se de um <\/span><b>documento que comprova que a sua empresa n\u00e3o tem nenhum tipo de irregularidade junto a \u00f3rg\u00e3os governamentais.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A CND, como tamb\u00e9m pode ser identificada, costuma ser solicitada v\u00e1rias vezes ao longo da exist\u00eancia de um neg\u00f3cio, por exemplo, na requisi\u00e7\u00e3o de um <\/span><a href=\"https:\/\/nfe.io\/blog\/financeiro\/emprestimo-empresarial\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">empr\u00e9stimo empresarial<\/span><\/a><span style=\"font-weight: 400;\"> ou quando a empresa vai participar de uma licita\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas em quais outros momentos uma Certid\u00e3o Negativa de D\u00e9bitos pode ser requerida? Quais s\u00e3o os tipos de CND existentes? Como emiti-las? Confira essas e outras respostas neste artigo!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2>O que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos?<\/h2>\n<p><span style=\"font-weight: 400;\">Saber o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos \u00e9 essencial para o crescimento da sua empresa e faz parte da <\/span><a href=\"https:\/\/nfe.io\/blog\/gestao-empresarial\/gestao-estrategica-para-empresas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">gest\u00e3o<\/span><\/a><span style=\"font-weight: 400;\"> de qualquer neg\u00f3cio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Certid\u00e3o Negativa de D\u00e9bitos, ou simplesmente CND, \u00e9 um <\/span><b>documento que comprova que a sua empresa n\u00e3o tem nenhum d\u00e9bito ou pend\u00eancia junto aos \u00f3rg\u00e3os governamentais<\/b>, <strong>e<\/strong> <b>pode ser emitida no \u00e2mbito municipal, estadual e\/ou federal<\/b>.<\/p>\n<p><span style=\"font-weight: 400;\">Ela vai informar se h\u00e1 quest\u00f5es tribut\u00e1rias, financeiras, previdenci\u00e1rias a serem resolvidas, bem como processuais contra o seu CNPJ.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esse documento comprova, por exemplo, se a sua empresa est\u00e1 respondendo algum processo, se est\u00e1 em dia com o pagamento de encargos trabalhistas, com o recolhimento de impostos, entre outros pontos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dica de leitura: \u201c<\/span><a href=\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Quais impostos uma empresa paga? Saiba de uma vez por todas como calcular os impostos de uma empresa<\/span><\/a><span style=\"font-weight: 400;\">\u201d<\/span><\/p>\n<h2>Qual a import\u00e2ncia da Certid\u00e3o Negativa de D\u00e9bitos?<\/h2>\n<p><span style=\"font-weight: 400;\">Agora que o conceito sobre o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos ficou mais claro, \u00e9 essencial que voc\u00ea entenda tamb\u00e9m qual a import\u00e2ncia desse documento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A CND \u00e9 importante para o seu neg\u00f3cio, pois <\/span><b>comprova de maneira simples e r\u00e1pida se a sua empresa est\u00e1, ou n\u00e3o, cumprindo todas as leis, compromissos financeiros e obriga\u00e7\u00f5es que a cerca.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Por exemplo, imagine que voc\u00ea vai solicitar um financiamento junto a um banco e um dos requisitos para aprova\u00e7\u00e3o \u00e9 a comprova\u00e7\u00e3o do pagamento dos impostos ao longo do \u00faltimo ano.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao inv\u00e9s de recolher todas as guias e apresentar cada uma delas, basta emitir uma CND do \u00f3rg\u00e3o correspondente e obter a informa\u00e7\u00e3o se a sua empresa est\u00e1 ou n\u00e3o em dia com esse compromisso.<\/span><\/p>\n<h2>Em quais situa\u00e7\u00f5es uma CND pode ser solicitada?<\/h2>\n<p><span style=\"font-weight: 400;\">N\u00e3o s\u00e3o raros os momentos que uma CND \u00e9 requerida ao longo da vida de uma empresa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, al\u00e9m de saber o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos, \u00e9 bem importante que voc\u00ea tenha conhecimento de quando esse documento pode ser solicitado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A Certid\u00e3o Negativa de D\u00e9bito pode ser solicitada para:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">participa\u00e7\u00e3o em licita\u00e7\u00f5es p\u00fablicas;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">participa\u00e7\u00e3o de processos de concorr\u00eancia;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">acordos de parceria p\u00fablico-privada;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">homologa\u00e7\u00e3o de fornecedores;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">solicita\u00e7\u00e3o de empr\u00e9stimos e <\/span><a href=\"https:\/\/gyramais.com.br\/blog\/tipos-de-financiamento-empresas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">financiamentos<\/span><\/a><span style=\"font-weight: 400;\"> junto a bancos e institui\u00e7\u00f5es financeiras<\/span><\/li>\n<\/ul>\n<h2>Quais tipos de Certid\u00e3o Negativa de D\u00e9bitos existem?<\/h2>\n<p><span style=\"font-weight: 400;\">S\u00e3o v\u00e1rios os tipos de CND que podem ser emitidas, cada uma com objetivo espec\u00edfico e comprova\u00e7\u00e3o de determinada situa\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como estamos esclarecendo o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos e qual a import\u00e2ncia desse documento, nada mais adequado do que apresentar a voc\u00ea alguns exemplos que podem ser solicitados \u00e0 sua empresa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre os diversos tipos de CND existentes est\u00e3o:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Certid\u00e3o de Regularidade Fiscal Estadual;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Certid\u00e3o de Regularidade Fiscal Municipal;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Certid\u00e3o Negativa de Tributos Imobili\u00e1rios;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Certid\u00e3o Negativa de D\u00e9bitos Trabalhistas;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Certid\u00e3o Negativa de D\u00e9bitos Previdenci\u00e1rios;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Certid\u00e3o Negativa de Execu\u00e7\u00f5es Fiscais;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Certid\u00e3o Negativa de Fal\u00eancia e Concordata;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Certid\u00e3o Negativa de D\u00e9bitos Relativos a Tributos Federais e \u00e0 D\u00edvida Ativa da Uni\u00e3o.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Considerando as vari\u00e1veis de CND no que se refere a pend\u00eancias tribut\u00e1rias, pode ser que a sua empresa tamb\u00e9m precise apresentar as chamadas Certid\u00e3o Positiva de D\u00e9bitos e Certid\u00e3o Positiva de D\u00e9bitos com Efeito de Negativa.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Certid\u00e3o Positiva de D\u00e9bitos<\/b><span style=\"font-weight: 400;\">: utilizada para comprovar a exist\u00eancia de d\u00edvidas tribut\u00e1rias;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Certid\u00e3o Positiva de D\u00e9bitos com Efeito de Negativa<\/b><span style=\"font-weight: 400;\">: esse documento comprova a exist\u00eancia de d\u00e9bitos, por\u00e9m sua exigibilidade est\u00e1 suspensa com base no <\/span><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l5172compilado.htm\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">artigo 151 do C\u00f3digo Tribut\u00e1rio Nacional<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/li>\n<\/ul>\n<h2>Como emitir Certid\u00e3o Negativa de D\u00e9bitos?<\/h2>\n<p><span style=\"font-weight: 400;\">Na explica\u00e7\u00e3o inicial sobre o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos citamos que esse documento pode ser emitido no \u00e2mbito municipal, estadual e federal, se lembra?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Assim, a CND pode ser gerada, por exemplo, junto \u00e0:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Receita Federal<\/b><span style=\"font-weight: 400;\">: para identificar quanto ao cumprimento de compromissos e obriga\u00e7\u00f5es relacionados aos tributos federais e Previd\u00eancia Social;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Secretarias da Fazenda Municipais<\/b><span style=\"font-weight: 400;\">: aponta se h\u00e1, ou n\u00e3o, pend\u00eancias junto \u00e0 prefeitura onde a empresa est\u00e1 instalada;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Justi\u00e7a do Trabalho<\/b><span style=\"font-weight: 400;\">: relata se a empresa tem alguma irregularidade trabalhista, tais como processos;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Tribunal de Justi\u00e7a<\/b><span style=\"font-weight: 400;\">: relativo a quest\u00f5es como processos de fal\u00eancia, concordatas, recupera\u00e7\u00e3o judicial, entre outras;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Fundo de Garantia por Tempo de Servi\u00e7o<\/b><span style=\"font-weight: 400;\">: comprova se a empresa est\u00e1 em dia com o recolhimento do FGTS dos funcion\u00e1rios.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Por conta disso, para <\/span><b>emitir cada tipo de CND \u00e9 preciso buscar os \u00f3rg\u00e3os respons\u00e1veis.<\/b><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Aproveite e leia tamb\u00e9m<\/strong>: <\/span><\/p>\n<ul>\n<li><a href=\"https:\/\/nfe.io\/blog\/nota-fiscal\/o-que-e-sefaz\/\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">O que \u00e9 SEFAZ, como funciona e o que significa para empresas<\/span><\/a><\/li>\n<li data-pm-slice=\"1 1 []\"><a href=\"https:\/\/nfe.io\/blog\/nota-fiscal\/como-consultar-nfe-sefaz\/\">Como consultar NF-e na Sefaz? 3 passos simples!<\/a><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">De modo geral, esses documentos s\u00e3o gratuitos e emitidos via internet. Mas \u00e9 importante que voc\u00ea saiba que algumas prefeituras podem exigir a presen\u00e7a do requerente ou mesmo o pagamento de uma taxa para emiss\u00e3o da CND.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, no que diz respeito \u00e0s Certid\u00f5es Negativas de D\u00e9bitos municipais, \u00e9 interessante entrar em contato com a prefeitura ou Secretaria da Fazenda Municipal para verificar quais s\u00e3o as exig\u00eancias.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No mais, confira alguns links que podem lhe ajudar a emitir desses documentos comprobat\u00f3rios:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"http:\/\/receita.economia.gov.br\/orientacao\/tributaria\/certidoes-e-situacao-fiscal\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Certid\u00e3o Negativa de D\u00e9bitos relativos aos Tributos Federais e D\u00edvida Ativa da Uni\u00e3o<\/span><\/a><span style=\"font-weight: 400;\">;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/consulta-crf.caixa.gov.br\/consultacrf\/pages\/consultaEmpregador.jsf\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Certid\u00e3o de FGTS<\/span><\/a><span style=\"font-weight: 400;\">;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"http:\/\/pesquisaprotesto.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Certid\u00e3o Negativa de Protesto;<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"http:\/\/www.tst.jus.br\/certidao\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Certid\u00e3o Negativa de D\u00e9bitos Trabalhistas (CNDT);<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/portal.trf1.jus.br\/Servicos\/Certidao\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Certid\u00e3o Negativa de D\u00e9bitos (CND).<\/span><\/a><\/li>\n<\/ul>\n<h2>Como melhorar a gest\u00e3o da sua empresa?<\/h2>\n<p><span style=\"font-weight: 400;\">Ficou claro o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos e a import\u00e2ncia desse documento para o seu neg\u00f3cio?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vale lembrar que nem sempre a exist\u00eancia de um d\u00e9bito \u00e9 decorrente da m\u00e1-f\u00e9 do empreendedor. Os d\u00e9bitos relacionados ao recolhimento de impostos, por exemplo, podem ser decorrentes de uma <\/span><a href=\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-gestao-fiscal\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">gest\u00e3o fiscal<\/span><\/a><span style=\"font-weight: 400;\"> ineficiente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para evitar que voc\u00ea cometa erros como esse, leia o artigo \u201c<\/span><a href=\"https:\/\/nfe.io\/blog\/financeiro\/dicas-gestao-financeira-empresas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">11 excelentes dicas de gest\u00e3o financeira para empresas: seus neg\u00f3cios v\u00e3o decolar!<\/span><\/a><span style=\"font-weight: 400;\">\u201d e confira como deixar os seus processos mais eficientes.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabe o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos? Trata-se de um documento que comprova que a sua empresa n\u00e3o tem nenhum tipo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":9108,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-9107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-financeiro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos? Como emitir?<\/title>\n<meta name=\"description\" content=\"Veja como comprovar que a sua empresa est\u00e1 livre de pend\u00eancias junto aos \u00f3rg\u00e3os governamentais. Confira o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos? Como emitir?\" \/>\n<meta property=\"og:description\" content=\"Veja como comprovar que a sua empresa est\u00e1 livre de pend\u00eancias junto aos \u00f3rg\u00e3os governamentais. Confira o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/\" \/>\n<meta property=\"og:site_name\" content=\"NFE.io Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nfe.io\" \/>\n<meta property=\"article:author\" content=\"https:\/\/fb.com\/gblmarquez\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-30T11:00:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-30T10:43:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nfe.io\/blog\/app\/uploads\/2021\/02\/o-que-e-certidao-negativa-de-debitos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gabriel Marquez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gblmarquez\" \/>\n<meta name=\"twitter:site\" content=\"@nfe_io\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Marquez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/\"},\"author\":{\"name\":\"Gabriel Marquez\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/5dba936eb6ef9ce2b7cd1bf6fb7aad11\"},\"headline\":\"O que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos e a import\u00e2ncia para a empresa\",\"datePublished\":\"2021-03-30T11:00:31+00:00\",\"dateModified\":\"2025-06-30T10:43:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/\"},\"wordCount\":1171,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nfe.io\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2021\/02\/o-que-e-certidao-negativa-de-debitos.png\",\"articleSection\":[\"Gest\u00e3o Financeira\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/\",\"url\":\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/\",\"name\":\"O que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos? Como emitir?\",\"isPartOf\":{\"@id\":\"https:\/\/nfe.io\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2021\/02\/o-que-e-certidao-negativa-de-debitos.png\",\"datePublished\":\"2021-03-30T11:00:31+00:00\",\"dateModified\":\"2025-06-30T10:43:21+00:00\",\"description\":\"Veja como comprovar que a sua empresa est\u00e1 livre de pend\u00eancias junto aos \u00f3rg\u00e3os governamentais. Confira o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos\",\"breadcrumb\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#primaryimage\",\"url\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2021\/02\/o-que-e-certidao-negativa-de-debitos.png\",\"contentUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2021\/02\/o-que-e-certidao-negativa-de-debitos.png\",\"width\":700,\"height\":500,\"caption\":\"certid\u00e3o negativa de d\u00e9bitos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nfe.io\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos e a import\u00e2ncia para a empresa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nfe.io\/blog\/#website\",\"url\":\"https:\/\/nfe.io\/blog\/\",\"name\":\"NFE.io Blog\",\"description\":\"Automatize Suas Obriga\u00e7\u00f5es Fiscais com Efici\u00eancia\",\"publisher\":{\"@id\":\"https:\/\/nfe.io\/blog\/#organization\"},\"alternateName\":\"NFE.io\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nfe.io\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nfe.io\/blog\/#organization\",\"name\":\"NFE io\",\"alternateName\":\"NFE\",\"url\":\"https:\/\/nfe.io\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png\",\"contentUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png\",\"width\":143,\"height\":41,\"caption\":\"NFE io\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nfe.io\",\"https:\/\/x.com\/nfe_io\",\"https:\/\/github.com\/nfe\",\"https:\/\/www.linkedin.com\/company\/10407705\/\",\"https:\/\/www.youtube.com\/channel\/UCB1PFw8rxeIN64k_t5FWEAQ\",\"https:\/\/www.instagram.com\/nfe.io\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/5dba936eb6ef9ce2b7cd1bf6fb7aad11\",\"name\":\"Gabriel Marquez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b9c35eac9573908c93a925466c8998ae2075037e3ccc57d03dea6faba89907ba?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b9c35eac9573908c93a925466c8998ae2075037e3ccc57d03dea6faba89907ba?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Gabriel Marquez\"},\"description\":\"Empreendedor e Fundador da NFE.io e outras startups. Focado em ajudar empreendedores a escalar seus neg\u00f3cios. Interessado? Marque um papo!\",\"sameAs\":[\"https:\/\/nfe.io\",\"https:\/\/fb.com\/gblmarquez\",\"https:\/\/br.linkedin.com\/in\/gblmarquez\",\"https:\/\/x.com\/gblmarquez\"],\"url\":\"https:\/\/nfe.io\/blog\/author\/gabrielmarquez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos? Como emitir?","description":"Veja como comprovar que a sua empresa est\u00e1 livre de pend\u00eancias junto aos \u00f3rg\u00e3os governamentais. Confira o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/","og_locale":"en_US","og_type":"article","og_title":"O que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos? Como emitir?","og_description":"Veja como comprovar que a sua empresa est\u00e1 livre de pend\u00eancias junto aos \u00f3rg\u00e3os governamentais. Confira o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos","og_url":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/","og_site_name":"NFE.io Blog","article_publisher":"https:\/\/www.facebook.com\/nfe.io","article_author":"https:\/\/fb.com\/gblmarquez","article_published_time":"2021-03-30T11:00:31+00:00","article_modified_time":"2025-06-30T10:43:21+00:00","og_image":[{"width":700,"height":500,"url":"https:\/\/nfe.io\/blog\/app\/uploads\/2021\/02\/o-que-e-certidao-negativa-de-debitos.png","type":"image\/png"}],"author":"Gabriel Marquez","twitter_card":"summary_large_image","twitter_creator":"@gblmarquez","twitter_site":"@nfe_io","twitter_misc":{"Written by":"Gabriel Marquez","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#article","isPartOf":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/"},"author":{"name":"Gabriel Marquez","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/5dba936eb6ef9ce2b7cd1bf6fb7aad11"},"headline":"O que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos e a import\u00e2ncia para a empresa","datePublished":"2021-03-30T11:00:31+00:00","dateModified":"2025-06-30T10:43:21+00:00","mainEntityOfPage":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/"},"wordCount":1171,"commentCount":0,"publisher":{"@id":"https:\/\/nfe.io\/blog\/#organization"},"image":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#primaryimage"},"thumbnailUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2021\/02\/o-que-e-certidao-negativa-de-debitos.png","articleSection":["Gest\u00e3o Financeira"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/","url":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/","name":"O que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos? Como emitir?","isPartOf":{"@id":"https:\/\/nfe.io\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#primaryimage"},"image":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#primaryimage"},"thumbnailUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2021\/02\/o-que-e-certidao-negativa-de-debitos.png","datePublished":"2021-03-30T11:00:31+00:00","dateModified":"2025-06-30T10:43:21+00:00","description":"Veja como comprovar que a sua empresa est\u00e1 livre de pend\u00eancias junto aos \u00f3rg\u00e3os governamentais. Confira o que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos","breadcrumb":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#primaryimage","url":"https:\/\/nfe.io\/blog\/app\/uploads\/2021\/02\/o-que-e-certidao-negativa-de-debitos.png","contentUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2021\/02\/o-que-e-certidao-negativa-de-debitos.png","width":700,"height":500,"caption":"certid\u00e3o negativa de d\u00e9bitos"},{"@type":"BreadcrumbList","@id":"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-certidao-negativa-de-debitos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nfe.io\/blog\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 Certid\u00e3o Negativa de D\u00e9bitos e a import\u00e2ncia para a empresa"}]},{"@type":"WebSite","@id":"https:\/\/nfe.io\/blog\/#website","url":"https:\/\/nfe.io\/blog\/","name":"NFE.io Blog","description":"Automatize Suas Obriga\u00e7\u00f5es Fiscais com Efici\u00eancia","publisher":{"@id":"https:\/\/nfe.io\/blog\/#organization"},"alternateName":"NFE.io","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nfe.io\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nfe.io\/blog\/#organization","name":"NFE io","alternateName":"NFE","url":"https:\/\/nfe.io\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png","contentUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png","width":143,"height":41,"caption":"NFE io"},"image":{"@id":"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nfe.io","https:\/\/x.com\/nfe_io","https:\/\/github.com\/nfe","https:\/\/www.linkedin.com\/company\/10407705\/","https:\/\/www.youtube.com\/channel\/UCB1PFw8rxeIN64k_t5FWEAQ","https:\/\/www.instagram.com\/nfe.io\/"]},{"@type":"Person","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/5dba936eb6ef9ce2b7cd1bf6fb7aad11","name":"Gabriel Marquez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b9c35eac9573908c93a925466c8998ae2075037e3ccc57d03dea6faba89907ba?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b9c35eac9573908c93a925466c8998ae2075037e3ccc57d03dea6faba89907ba?s=96&d=wp_user_avatar&r=g","caption":"Gabriel Marquez"},"description":"Empreendedor e Fundador da NFE.io e outras startups. Focado em ajudar empreendedores a escalar seus neg\u00f3cios. Interessado? Marque um papo!","sameAs":["https:\/\/nfe.io","https:\/\/fb.com\/gblmarquez","https:\/\/br.linkedin.com\/in\/gblmarquez","https:\/\/x.com\/gblmarquez"],"url":"https:\/\/nfe.io\/blog\/author\/gabrielmarquez\/"}]}},"_links":{"self":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts\/9107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/comments?post=9107"}],"version-history":[{"count":1,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts\/9107\/revisions"}],"predecessor-version":[{"id":13320,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts\/9107\/revisions\/13320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/media\/9108"}],"wp:attachment":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/media?parent=9107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/categories?post=9107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/tags?post=9107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}