{"id":7125,"date":"2019-09-26T08:00:58","date_gmt":"2019-09-26T11:00:58","guid":{"rendered":"https:\/\/nfe.io\/blog\/?p=7125"},"modified":"2022-03-17T15:14:03","modified_gmt":"2022-03-17T18:14:03","slug":"o-que-e-iugu","status":"publish","type":"post","link":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/","title":{"rendered":"O que \u00e9 iugu: o gateway para pagamentos que pode fazer a diferen\u00e7a na sua loja virtual"},"content":{"rendered":"<p>Voc\u00ea sabe o que \u00e9 iugu?<\/p>\n<p>Se voc\u00ea est\u00e1 a procura de um gateway de pagamentos online, ent\u00e3o, esta talvez seja a solu\u00e7\u00e3o ideal.<\/p>\n<p>Continue a leitura para conhecer o que \u00e9 iugu, suas funcionalidades e principais vantagens que v\u00e3o te convencer a implementar esta plataforma no seu neg\u00f3cio.<\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot; \n\n\t&lt;div class=&quot;cta-blog dark bar&quot; id=&quot;7125&quot;&gt;\n\n\t\t&lt;div class=&quot;cta-title&quot;&gt;\n\t\t\t&lt;h3&gt; &lt;\/h3&gt;\n\t\t&lt;\/div&gt;\n\n\t\t&lt;div class=&quot;cta-content&quot;&gt;\n\t\t\t&lt;p&gt;&lt;\/p&gt;\n\t\t&lt;\/div&gt;\n\n\t\t&lt;div class=&quot;cta-area&quot;&gt;\n\n\t\t\t&lt;!-- &lt;div class=&quot;left&quot;&gt;\n\t\t\t\t&lt;h5&gt;&lt;\/h5&gt;\n\t\t\t\t&lt;div id=&quot;subtitle&quot;&gt;&lt;\/div&gt;\n\t\t\t&lt;\/div&gt; --&gt;\n\n\t\t\t&lt;!-- &lt;div class=&quot;right&quot;&gt; --&gt;\n\t\t\t\t\t\t\t&lt;!-- &lt;\/div&gt; --&gt;\n\n\t\t&lt;\/div&gt;\n\n\t&lt;\/div&gt;\n\n\t&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:961,&quot;3&quot;:{&quot;1&quot;:0},&quot;9&quot;:1,&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\"><\/span><\/p>\n<h2>O que \u00e9 iugu?<\/h2>\n<p>Criada em 2013, a <strong><a href=\"https:\/\/iugu.com\/\">iugu<\/a> <\/strong>\u00e9 uma plataforma para pagamentos online que promete simplificar os processos financeiros da sua empresa e alavancar sua produtividade.<\/p>\n<p>A empresa foi pioneira em oferecer um sistema completo para pagamentos que se adequa \u00e0s necessidades do seu neg\u00f3cio.<\/p>\n<p><a href=\"https:\/\/www.venki.com.br\/blog\/empresas-saas\/\" target=\"_blank\" rel=\"noopener\"><strong>Empresas de SaaS<\/strong><\/a>, marketplaces, lojas virtuais e clubes de assinatura s\u00e3o alguns exemplos de modelos de neg\u00f3cio que podem se beneficiar com a iugu. Isso porque a plataforma ajuda a promover uma gest\u00e3o de cobran\u00e7a mais eficiente.<\/p>\n<p>A iugu se destina a neg\u00f3cios digitais, n\u00e3o sendo, assim, indicada para empresas que atuam no mercado offline. Al\u00e9m disso, a plataforma n\u00e3o encontra-se dispon\u00edvel para quem \u00e9 Microempreendedor Individual (MEI).<\/p>\n<p>Quer conhecer a iugi ainda nelhor? Ent\u00e3o, confira este v\u00eddeo:<\/p>\n<p><iframe loading=\"lazy\" title=\"A Transforma\u00e7\u00e3o Digital para a sua empresa | iugu\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/am2nk_Bjngc?start=23&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>DICA:\u00a0<strong><a href=\"https:\/\/nfe.io\/blog\/pagamentos\/iugu-api\/\">API IUGU: conhe\u00e7a os benef\u00edcios e aprenda a criar automatiza\u00e7\u00f5es<\/a><\/strong><\/p>\n<h2>Quais vantagens a iugu oferece?<\/h2>\n<p>Agora que voc\u00ea j\u00e1 sabe o que \u00e9 iugu, vamos \u00e0s vantagens que essa plataforma oferece.<\/p>\n<h3>Gest\u00e3o de pagamentos recorrentes<\/h3>\n<p>Muitas empresas de com\u00e9rcio online est\u00e3o trabalhando com o modelo de pagamento recorrente. Se, por exemplo, voc\u00ea for dono de um clube de assinatura, a iugu te ajuda a fazer a gest\u00e3o dos seus recebimentos, oferecendo:<\/p>\n<ul>\n<li>Diferentes modalidades de planos de assinatura;<\/li>\n<li>Per\u00edodo de free trial;<\/li>\n<li>Flexibilidade no pagamento do plano;<\/li>\n<li>Possibilidade de o cliente adquirir itens adicionais a serem inclu\u00eddos na fatura do m\u00eas em quest\u00e3o;<\/li>\n<li>Possibilidade de alterar o plano a qualquer momento (upgrade ou downgrade) com c\u00e1lculos proporcionais.<\/li>\n<\/ul>\n<p>Leia tamb\u00e9m:\u00a0<strong><a href=\"https:\/\/nfe.io\/blog\/assinatura\/gestao-pagamento-recorrente\/\">Gest\u00e3o de pagamento recorrente: 6 dicas para ser mais eficiente com esse modelo de cobran\u00e7a<\/a><\/strong><\/p>\n<h3>Transpar\u00eancia no checkout<\/h3>\n<p>Com a plataforma iugu, seu cliente far\u00e1 toda a transa\u00e7\u00e3o dentro do pr\u00f3prio site da sua loja, sem precisar, dessa forma, ser redirecionado para outro endere\u00e7o. Dessa forma, voc\u00ea confere mais agilidade ao processo de compra e contribui para que o cliente se sinta mais seguro ao comprar na sua loja online.<\/p>\n<h3>Possibilidade de parcelamento das compras<\/h3>\n<p>As compras feitas pela plataforma iugu podem ser parceladas em at\u00e9 12 vezes no cart\u00e3o de cr\u00e9dito. Al\u00e9m disso, \u00e9 poss\u00edvel fazer configura\u00e7\u00e3o para que os juros podem sejam arcados pelo vendedor ou pelo comprador.<\/p>\n<h3>Compras mais \u00e1geis<\/h3>\n<p>Com o gateway da iugu, seus clientes podem efetuar suas compras em 1 clique. Isso porque, ap\u00f3s efetuarem o cadastro na primeira compra, os dados ficar\u00e3o armazenados para que, na pr\u00f3xima compra, n\u00e3o seja necess\u00e1rio preencher todos os campos novamente.<\/p>\n<p>Assim, basta escolher o produto e comprar.<\/p>\n<h3>Gest\u00e3o de cobran\u00e7a<\/h3>\n<p>Para evitar a inadimpl\u00eancia, a iugu te auxilia tamb\u00e9m na gest\u00e3o de cobran\u00e7a do seu neg\u00f3cio online. A plataforma permite que voc\u00ea envie e-mail transacionais para seus clientes para avis\u00e1-los sobre a aproxima\u00e7\u00e3o da data de vencimento de alguma fatura ou para alert\u00e1-los sobre atrasos no pagamento.<\/p>\n<h3>Integra\u00e7\u00e3o via API<\/h3>\n<p>Voc\u00ea pode integrar a iugu a outras ferramentas do seu interesse via API, que \u00e9 um protocolo da internet que permite a troca de informa\u00e7\u00f5es entre duas plataformas.<\/p>\n<h3>Intelig\u00eancia financeira<\/h3>\n<p>A iugu oferece dados valiosos para a estrat\u00e9gia do seu neg\u00f3cio online. Com eles, \u00e9 poss\u00edvel acompanhar a evolu\u00e7\u00e3o da sua loja virtual sob diferentes aspectos.<\/p>\n<p>Confira abaixo alguns dados que a intelig\u00eancia financeira da iugu te d\u00e1 acesso:<\/p>\n<ul>\n<li>Movimenta\u00e7\u00e3o do fluxo de caixa;<\/li>\n<li>Gr\u00e1ficos sobre a movimenta\u00e7\u00e3o de receita corrente;<\/li>\n<li>Previs\u00f5es de receita<\/li>\n<li>Transa\u00e7\u00f5es pagas;<\/li>\n<li>Taxa de churn.<\/li>\n<\/ul>\n<h3>Pagamentos por tokens<\/h3>\n<p>O pagamento via tokens confere total seguran\u00e7a para o processo de compra. Quando o cliente insere seus dados para pagamento, \u00e9 gerada uma chave de seguran\u00e7a (token) que s\u00f3 ele ter\u00e1 acesso. Assim, a compra s\u00f3 \u00e9 efetuada quando \u00e9 feito o correto cruzamento entre token, conta do cliente e valida\u00e7\u00e3o do aparelho.<\/p>\n<p>Al\u00e9m disso, todos os dados s\u00e3o criptografados de ponta a ponta.<\/p>\n<h2>Quais s\u00e3o as taxas praticadas pela iugu?<\/h2>\n<p>O meio de <strong><a href=\"https:\/\/pluga.co\/blog\/financeiro\/pagamento-digital\/\" target=\"_blank\" rel=\"noopener\">pagamento digital<\/a><\/strong> iugu apresenta duas modalidades para cobran\u00e7a de taxas. A primeira est\u00e1 atrelada a forma de pagamento e ao parcelamento da compra. Por outro lado, a segunda modalidade varia de acordo com o volume de vendas mensal.<\/p>\n<h3>Modalidade 1 &#8211; Forma de pagamento e parcelamento<\/h3>\n<ul>\n<li>2,51% para cada venda feita \u00e0 vista no cart\u00e3o de cr\u00e9dito;<\/li>\n<li>3,21% para cada venda parcelada entre 2 e 6 vezes;<\/li>\n<li>3,55% para parcelamento entre 7 e 12 vezes;<\/li>\n<li>4,60% para cada venda pelo cart\u00e3o de cr\u00e9dito American Express;<\/li>\n<li>1,28% para vendas pelo boleto banc\u00e1rio.<\/li>\n<\/ul>\n<h3>Modalidade 2 &#8211; Volume de vendas mensal<\/h3>\n<ul>\n<li>At\u00e9 200 reais\u00a0 = sem taxa<\/li>\n<li>1.000 reais = R$0,70<\/li>\n<li>2.000 reais = R$0,60<\/li>\n<li>4.000 reais = R$0,55<\/li>\n<li>8.000 reais = R$0,50<\/li>\n<li>16.000 reais = R$0,40<\/li>\n<li>32.000 reais = R$0,30<\/li>\n<li>62.000 reais = R$0,20<\/li>\n<li>128.000 reais = R$0,10<\/li>\n<li>Acima de 128.000 reais = R$0,08<\/li>\n<\/ul>\n<p>Agora que voc\u00ea j\u00e1 sabe o que \u00e9 iugu e as funcionalidades dessa plataforma, que tal implement\u00e1-la no seu ecommerce?<\/p>\n<p>Saiba mais:\u00a0<strong><a href=\"https:\/\/nfe.io\/blog\/pagamentos\/iugu-pagamentos\/\">Iugu pagamentos: um dos mais completos meios de pagamento<\/a><\/strong><\/p>\n<h2>Emita suas notas fiscais com o NFE.io<\/h2>\n<p>Fa\u00e7a a emiss\u00e3o autom\u00e1tica de sua notas fiscais com o NFE.io, assim, sua opera\u00e7\u00e3o se torna mais \u00e1gil e segura.<\/p>\n<p>Al\u00e9m disso, ele j\u00e1 faz o c\u00e1lculos das notas fiscais, e tamb\u00e9m gera os arquivos XML e HTML e os envia para os clientes. E mais, se o site da prefeitura estiver fora do do ar, ele reenvia a nota at\u00e9 que a conex\u00e3o se restabele\u00e7a. Dessa forma, voc\u00ea n\u00e3o precisa se preocupar em enviar novamente.<\/p>\n<p>Quer saber mais sobre o NFE.io? <a href=\"https:\/\/nfe.io\/#contato\"><strong>Ent\u00e3o, marque uma conversa!<\/strong><\/a><\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot; \n\n\t&lt;div class=&quot;cta-blog dark io&quot; id=&quot;7125&quot;&gt;\n\n\t\t&lt;div class=&quot;cta-title&quot;&gt;\n\t\t\t&lt;h3&gt; &lt;\/h3&gt;\n\t\t&lt;\/div&gt;\n\n\t\t&lt;div class=&quot;cta-content&quot;&gt;\n\t\t\t&lt;p&gt;&lt;\/p&gt;\n\t\t&lt;\/div&gt;\n\n\t\t&lt;div class=&quot;cta-area&quot;&gt;\n\n\t\t\t&lt;!-- &lt;div class=&quot;left&quot;&gt;\n\t\t\t\t&lt;h5&gt;&lt;\/h5&gt;\n\t\t\t\t&lt;div id=&quot;subtitle&quot;&gt;&lt;\/div&gt;\n\t\t\t&lt;\/div&gt; --&gt;\n\n\t\t\t&lt;!-- &lt;div class=&quot;right&quot;&gt; --&gt;\n\t\t\t\t\t\t\t&lt;!-- &lt;\/div&gt; --&gt;\n\n\t\t&lt;\/div&gt;\n\n\t&lt;\/div&gt;\n\n\t&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:705,&quot;3&quot;:{&quot;1&quot;:0},&quot;9&quot;:1,&quot;10&quot;:1,&quot;12&quot;:0}\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabe o que \u00e9 iugu? Se voc\u00ea est\u00e1 a procura de um gateway de pagamentos online, ent\u00e3o, esta talvez seja a solu\u00e7\u00e3o&#8230;<\/p>\n","protected":false},"author":2,"featured_media":7132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-7125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pagamentos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O que \u00e9 iugu? Para que serve? Quais as principais vantagens?<\/title>\n<meta name=\"description\" content=\"Entenda o que \u00e9 iugu, para que essa plataforma serve, suas principais vantagens e como ela pode ajudar no seu com\u00e9rcio eletr\u00f4nico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 iugu? Para que serve? Quais as principais vantagens?\" \/>\n<meta property=\"og:description\" content=\"Entenda o que \u00e9 iugu, para que essa plataforma serve, suas principais vantagens e como ela pode ajudar no seu com\u00e9rcio eletr\u00f4nico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/\" \/>\n<meta property=\"og:site_name\" content=\"NFE.io Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nfe.io\" \/>\n<meta property=\"article:author\" content=\"https:\/\/fb.com\/gblmarquez\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-26T11:00:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-17T18:14:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/09\/o-que-e-iugu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriel Marquez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gblmarquez\" \/>\n<meta name=\"twitter:site\" content=\"@nfe_io\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Marquez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/\"},\"author\":{\"name\":\"Gabriel Marquez\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/5dba936eb6ef9ce2b7cd1bf6fb7aad11\"},\"headline\":\"O que \u00e9 iugu: o gateway para pagamentos que pode fazer a diferen\u00e7a na sua loja virtual\",\"datePublished\":\"2019-09-26T11:00:58+00:00\",\"dateModified\":\"2022-03-17T18:14:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/\"},\"wordCount\":1013,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nfe.io\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/09\/o-que-e-iugu.jpg\",\"articleSection\":[\"Meios de Pagamento\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/\",\"url\":\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/\",\"name\":\"O que \u00e9 iugu? Para que serve? Quais as principais vantagens?\",\"isPartOf\":{\"@id\":\"https:\/\/nfe.io\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/09\/o-que-e-iugu.jpg\",\"datePublished\":\"2019-09-26T11:00:58+00:00\",\"dateModified\":\"2022-03-17T18:14:03+00:00\",\"description\":\"Entenda o que \u00e9 iugu, para que essa plataforma serve, suas principais vantagens e como ela pode ajudar no seu com\u00e9rcio eletr\u00f4nico.\",\"breadcrumb\":{\"@id\":\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#primaryimage\",\"url\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/09\/o-que-e-iugu.jpg\",\"contentUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/09\/o-que-e-iugu.jpg\",\"width\":1000,\"height\":667,\"caption\":\"O que \u00e9 iugu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nfe.io\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 iugu: o gateway para pagamentos que pode fazer a diferen\u00e7a na sua loja virtual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nfe.io\/blog\/#website\",\"url\":\"https:\/\/nfe.io\/blog\/\",\"name\":\"NFE.io Blog\",\"description\":\"Automatize Suas Obriga\u00e7\u00f5es Fiscais com Efici\u00eancia\",\"publisher\":{\"@id\":\"https:\/\/nfe.io\/blog\/#organization\"},\"alternateName\":\"NFE.io\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nfe.io\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nfe.io\/blog\/#organization\",\"name\":\"NFE io\",\"alternateName\":\"NFE\",\"url\":\"https:\/\/nfe.io\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png\",\"contentUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png\",\"width\":143,\"height\":41,\"caption\":\"NFE io\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nfe.io\",\"https:\/\/x.com\/nfe_io\",\"https:\/\/github.com\/nfe\",\"https:\/\/www.linkedin.com\/company\/10407705\/\",\"https:\/\/www.youtube.com\/channel\/UCB1PFw8rxeIN64k_t5FWEAQ\",\"https:\/\/www.instagram.com\/nfe.io\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/5dba936eb6ef9ce2b7cd1bf6fb7aad11\",\"name\":\"Gabriel Marquez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b9c35eac9573908c93a925466c8998ae2075037e3ccc57d03dea6faba89907ba?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b9c35eac9573908c93a925466c8998ae2075037e3ccc57d03dea6faba89907ba?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Gabriel Marquez\"},\"description\":\"Empreendedor e Fundador da NFE.io e outras startups. Focado em ajudar empreendedores a escalar seus neg\u00f3cios. Interessado? Marque um papo!\",\"sameAs\":[\"https:\/\/nfe.io\",\"https:\/\/fb.com\/gblmarquez\",\"https:\/\/br.linkedin.com\/in\/gblmarquez\",\"https:\/\/x.com\/gblmarquez\"],\"url\":\"https:\/\/nfe.io\/blog\/author\/gabrielmarquez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 iugu? Para que serve? Quais as principais vantagens?","description":"Entenda o que \u00e9 iugu, para que essa plataforma serve, suas principais vantagens e como ela pode ajudar no seu com\u00e9rcio eletr\u00f4nico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/","og_locale":"en_US","og_type":"article","og_title":"O que \u00e9 iugu? Para que serve? Quais as principais vantagens?","og_description":"Entenda o que \u00e9 iugu, para que essa plataforma serve, suas principais vantagens e como ela pode ajudar no seu com\u00e9rcio eletr\u00f4nico.","og_url":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/","og_site_name":"NFE.io Blog","article_publisher":"https:\/\/www.facebook.com\/nfe.io","article_author":"https:\/\/fb.com\/gblmarquez","article_published_time":"2019-09-26T11:00:58+00:00","article_modified_time":"2022-03-17T18:14:03+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/09\/o-que-e-iugu.jpg","type":"image\/jpeg"}],"author":"Gabriel Marquez","twitter_card":"summary_large_image","twitter_creator":"@gblmarquez","twitter_site":"@nfe_io","twitter_misc":{"Written by":"Gabriel Marquez","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#article","isPartOf":{"@id":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/"},"author":{"name":"Gabriel Marquez","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/5dba936eb6ef9ce2b7cd1bf6fb7aad11"},"headline":"O que \u00e9 iugu: o gateway para pagamentos que pode fazer a diferen\u00e7a na sua loja virtual","datePublished":"2019-09-26T11:00:58+00:00","dateModified":"2022-03-17T18:14:03+00:00","mainEntityOfPage":{"@id":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/"},"wordCount":1013,"commentCount":0,"publisher":{"@id":"https:\/\/nfe.io\/blog\/#organization"},"image":{"@id":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#primaryimage"},"thumbnailUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/09\/o-que-e-iugu.jpg","articleSection":["Meios de Pagamento"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/","url":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/","name":"O que \u00e9 iugu? Para que serve? Quais as principais vantagens?","isPartOf":{"@id":"https:\/\/nfe.io\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#primaryimage"},"image":{"@id":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#primaryimage"},"thumbnailUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/09\/o-que-e-iugu.jpg","datePublished":"2019-09-26T11:00:58+00:00","dateModified":"2022-03-17T18:14:03+00:00","description":"Entenda o que \u00e9 iugu, para que essa plataforma serve, suas principais vantagens e como ela pode ajudar no seu com\u00e9rcio eletr\u00f4nico.","breadcrumb":{"@id":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#primaryimage","url":"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/09\/o-que-e-iugu.jpg","contentUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/09\/o-que-e-iugu.jpg","width":1000,"height":667,"caption":"O que \u00e9 iugu"},{"@type":"BreadcrumbList","@id":"https:\/\/nfe.io\/blog\/pagamentos\/o-que-e-iugu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nfe.io\/blog\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 iugu: o gateway para pagamentos que pode fazer a diferen\u00e7a na sua loja virtual"}]},{"@type":"WebSite","@id":"https:\/\/nfe.io\/blog\/#website","url":"https:\/\/nfe.io\/blog\/","name":"NFE.io Blog","description":"Automatize Suas Obriga\u00e7\u00f5es Fiscais com Efici\u00eancia","publisher":{"@id":"https:\/\/nfe.io\/blog\/#organization"},"alternateName":"NFE.io","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nfe.io\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nfe.io\/blog\/#organization","name":"NFE io","alternateName":"NFE","url":"https:\/\/nfe.io\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png","contentUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png","width":143,"height":41,"caption":"NFE io"},"image":{"@id":"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nfe.io","https:\/\/x.com\/nfe_io","https:\/\/github.com\/nfe","https:\/\/www.linkedin.com\/company\/10407705\/","https:\/\/www.youtube.com\/channel\/UCB1PFw8rxeIN64k_t5FWEAQ","https:\/\/www.instagram.com\/nfe.io\/"]},{"@type":"Person","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/5dba936eb6ef9ce2b7cd1bf6fb7aad11","name":"Gabriel Marquez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b9c35eac9573908c93a925466c8998ae2075037e3ccc57d03dea6faba89907ba?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b9c35eac9573908c93a925466c8998ae2075037e3ccc57d03dea6faba89907ba?s=96&d=wp_user_avatar&r=g","caption":"Gabriel Marquez"},"description":"Empreendedor e Fundador da NFE.io e outras startups. Focado em ajudar empreendedores a escalar seus neg\u00f3cios. Interessado? Marque um papo!","sameAs":["https:\/\/nfe.io","https:\/\/fb.com\/gblmarquez","https:\/\/br.linkedin.com\/in\/gblmarquez","https:\/\/x.com\/gblmarquez"],"url":"https:\/\/nfe.io\/blog\/author\/gabrielmarquez\/"}]}},"_links":{"self":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts\/7125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/comments?post=7125"}],"version-history":[{"count":0,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts\/7125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/media\/7132"}],"wp:attachment":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/media?parent=7125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/categories?post=7125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/tags?post=7125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}