{"id":6142,"date":"2019-03-08T05:00:27","date_gmt":"2019-03-08T08:00:27","guid":{"rendered":"https:\/\/nfe.io\/blog\/?p=6142"},"modified":"2022-03-02T12:29:10","modified_gmt":"2022-03-02T15:29:10","slug":"quais-impostos-uma-empresa-paga","status":"publish","type":"post","link":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/","title":{"rendered":"Quais impostos uma empresa paga? Saiba de uma vez por todas como calcular os impostos de uma empresa"},"content":{"rendered":"<p>Voc\u00ea gostaria de entender melhor como calcular impostos de uma empresa, mas ainda n\u00e3o sabe como?<\/p>\n<p>Normalmente, as notas fiscais especificam os impostos que estamos pagando, sejam de servi\u00e7os ou produtos. Mas entender melhor o assunto evita que haja qualquer tipo de problema, m\u00e1 interpreta\u00e7\u00e3o e at\u00e9 mesmo sonega\u00e7\u00e3o fiscal.<\/p>\n<p>Justamente por isso \u00e9 importante conhecer melhor os c\u00e1lculos e para que as cobran\u00e7as e tributa\u00e7\u00f5es servem. E para come\u00e7ar a controlar melhor as finan\u00e7as da empresa, que tal come\u00e7ar por um bom planejamento tribut\u00e1rio e pelo conhecimento de todos os principais impostos?<\/p>\n<p>Neste post, voc\u00ea vai descobrir quais impostos uma empresa paga, como calcular impostos de uma empresa e quais impostos diretos incidem sobre as empresas.<\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot; \n\n\t&lt;div class=&quot;cta-blog blue io&quot; id=&quot;6142&quot;&gt;\n\n\t\t&lt;div class=&quot;cta-title&quot;&gt;\n\t\t\t&lt;h3&gt; &lt;\/h3&gt;\n\t\t&lt;\/div&gt;\n\n\t\t&lt;div class=&quot;cta-content&quot;&gt;\n\t\t\t&lt;p&gt;&lt;\/p&gt;\n\t\t&lt;\/div&gt;\n\n\t\t&lt;div class=&quot;cta-area&quot;&gt;\n\n\t\t\t&lt;!-- &lt;div class=&quot;left&quot;&gt;\n\t\t\t\t&lt;h5&gt;&lt;\/h5&gt;\n\t\t\t\t&lt;div id=&quot;subtitle&quot;&gt;&lt;\/div&gt;\n\t\t\t&lt;\/div&gt; --&gt;\n\n\t\t\t&lt;!-- &lt;div class=&quot;right&quot;&gt; --&gt;\n\t\t\t\t\t\t\t&lt;!-- &lt;\/div&gt; --&gt;\n\n\t\t&lt;\/div&gt;\n\n\t&lt;\/div&gt;\n\n\t&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:962,&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:14281427},&quot;9&quot;:1,&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\"><\/span><\/p>\n<p><!--more--><\/p>\n<h2>Como calcular impostos de uma empresa utilizando planejamento tribut\u00e1rio<\/h2>\n<p>O planejamento tribut\u00e1rio \u00e9 uma forma legal de reduzir e calcular os custos de impostos de uma empresa de maneira simplificada.<\/p>\n<p>Existem basicamente\u00a0<a href=\"https:\/\/nfe.io\/blog\/financeiro\/tipos-de-planejamento-tributario\/\">tr\u00eas tipos de planejamento tribut\u00e1rio<\/a> no Brasil, que seria o estrat\u00e9gico, o operacional e o t\u00e1tico.<\/p>\n<p>Seja a curto, m\u00e9dio ou longo prazo, todos eles ajudam a empresa a alcan\u00e7ar seus objetivos com proje\u00e7\u00f5es e organiza\u00e7\u00f5es financeiras. Analisar a regi\u00e3o em que a empresa est\u00e1 situada, a estrutura e previs\u00e3o de crescimento, a \u00e1rea de atua\u00e7\u00e3o e a quantidade de funcion\u00e1rios, tudo isso pode influenciar no planejamento.<\/p>\n<p>Existe algo muito importante neste contexto que deve ser observado, que seria a defini\u00e7\u00e3o do enquadramento tribut\u00e1rio da empresa. S\u00e3o tamb\u00e9m tr\u00eas op\u00e7\u00f5es:<\/p>\n<ol>\n<li>Simples Nacional<\/li>\n<li>Lucro Presumido<\/li>\n<li>Lucro Real<\/li>\n<\/ol>\n<p>Diferentes <a href=\"https:\/\/www.nerus.com.br\/noticias\/processos\/saiba-como-a-sua-opcao-tributaria-afeta-o-seu-lucro\/\" target=\"_blank\" rel=\"noopener noreferrer\">op\u00e7\u00f5es tribut\u00e1rias v\u00e3o afetar seu lucro de formas diferentes<\/a>.<\/p>\n<p>Uma vez escolhido o regime tribut\u00e1rio que ser\u00e1 levado para o ano, fica mais f\u00e1cil consultar como calcular os impostos de uma empresa, cujas al\u00edquotas variam de acordo com o enquadramento.<\/p>\n<p>Quer mais dicas de como pagar imposto no regime de lucro presumido? Ent\u00e3o assista a este v\u00eddeo da AJ Solu\u00e7\u00f5es:<\/p>\n<p><iframe loading=\"lazy\" title=\"Calculando o Regime Tribut\u00e1rio Lucro Presumido na Pr\u00e1tica\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/xMQIO9AVRMg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Leia tamb\u00e9m em nosso blog e entenda melhor como calcular impostos de uma empresa:<\/p>\n<ul>\n<li><a href=\"https:\/\/nfe.io\/blog\/financeiro\/como-calcular-simples-nacional\/\">Como calcular o Simples Nacional na nova regra de 2018 \u2013 ATUALIZADO!<\/a><\/li>\n<li><a href=\"https:\/\/nfe.io\/blog\/financeiro\/como-calcular-impostos-lucro-presumido\/\">Como calcular impostos Lucro Presumido 2020? Descubra se o regime \u00e9 vantajoso para a sua empresa<\/a><\/li>\n<li><a href=\"https:\/\/nfe.io\/blog\/financeiro\/como-calcular-imposto-lucro-real\/\">Aprenda como calcular imposto lucro real 2020<\/a><\/li>\n<\/ul>\n<h2>Quais impostos uma empresa paga?<\/h2>\n<p>Ao gerar notas fiscais, que servem como comprovantes de opera\u00e7\u00f5es de compra e venda, existe uma s\u00e9rie de\u00a0<a href=\"https:\/\/nfe.io\/blog\/nota-fiscal\/imposto-sobre-nota-fiscal\/\">impostos que incidem sobre elas<\/a> e devem ser pagos pelas empresas.<\/p>\n<p>Separamos abaixo os principais para que voc\u00ea possa saber <a href=\"https:\/\/nfe.io\/blog\/nota-fiscal\/tudo-sobre-imposto-notas-fiscais\/\">como calcular<\/a> impostos de uma empresa com mais tranquilidade.<\/p>\n<p>Confira quais impostos uma empresa paga, isto \u00e9, quais impostos diretos incidem sobre as empresas!<\/p>\n<table dir=\"ltr\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"100\" \/>\n<col width=\"401\" \/><\/colgroup>\n<tbody>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;IRPJ&quot;}\">IRPJ<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;O Imposto de Renda Pessoa Jur\u00eddica (IRPJ) \u00e9 uma taxa cobrada de todas as empresas com cadastro jur\u00eddico. O c\u00e1lculo \u00e9 baseado no lucro da companhia. A al\u00edquota acaba sendo de 15% do lucro registrado e mais 10% quando o valor mensal apurado ultrapassa os R$ 20 mil.&quot;}\">O Imposto de Renda Pessoa Jur\u00eddica (IRPJ) \u00e9 uma taxa cobrada de todas as empresas com cadastro jur\u00eddico. O c\u00e1lculo \u00e9 baseado no lucro da companhia. A al\u00edquota acaba sendo de 15% do lucro registrado e mais 10% quando o valor mensal apurado ultrapassa os R$ 20 mil.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;COFINS&quot;}\">COFINS<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;A Contribui\u00e7\u00e3o para o Financiamento da Seguridade Social (COFINS) \u00e9 um tributo federal, que incide sobre a receita bruta das empresas. O c\u00e1lculo \u00e9 feito automaticamente com base no faturamento bruto e seu intuito \u00e9 financiar a sa\u00fade, a previd\u00eancia e assist\u00eancia social.\\n\\nComo a contribui\u00e7\u00e3o vigora em dois tipos de regimes diferentes (cumulativo, com al\u00edquota de 3% em cima do faturamento; e n\u00e3o cumulativo, 7,6%), voc\u00ea pode consultar neste texto mais sobre o c\u00e1lculo deste imposto em sua empresa.&quot;}\">A Contribui\u00e7\u00e3o para o Financiamento da Seguridade Social (COFINS) \u00e9 um tributo federal, que incide sobre a receita bruta das empresas. O c\u00e1lculo \u00e9 feito automaticamente com base no faturamento bruto e seu intuito \u00e9 financiar a sa\u00fade, a previd\u00eancia e assist\u00eancia social.<\/p>\n<p>Como a contribui\u00e7\u00e3o vigora em dois tipos de regimes diferentes (cumulativo, com al\u00edquota de 3% em cima do faturamento; e n\u00e3o cumulativo, 7,6%), voc\u00ea pode <a href=\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-cofins\/\" target=\"_blank\" rel=\"noopener noreferrer\">consultar neste texto<\/a> mais sobre o c\u00e1lculo deste imposto em sua empresa.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CSLL&quot;}\">CSLL<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;A Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido \u00e9 mais uma federal, que \u00e9 voltada \u00e0 seguridade social. O valor costuma ser de 10% a 12% do lucro l\u00edquido, mas o c\u00e1lculo exato ir\u00e1 variar de acordo com o enquadramento tribut\u00e1rio.&quot;}\">A Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido \u00e9 mais uma federal, que \u00e9 voltada \u00e0 seguridade social. O valor costuma ser de 10% a 12% do lucro l\u00edquido, mas o <a href=\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-csll\/\">c\u00e1lculo exato ir\u00e1 variar de acordo com o enquadramento tribut\u00e1rio<\/a>.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;PIS&quot;}\">PIS<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;O Programa de Integra\u00e7\u00e3o Social (PIS) financia o seguro-desemprego e o abono salarial de profissionais (setor privado). Para o setor p\u00fablico, o tributo \u00e9 o PASEP (Programa de Forma\u00e7\u00e3o do Patrim\u00f4nio do Servidor P\u00fablico). O tributo tamb\u00e9m vem especificado sobre as notas fiscais emitidas.&quot;}\">O Programa de Integra\u00e7\u00e3o Social (PIS) financia o seguro-desemprego e o abono salarial de profissionais (setor privado). Para o setor p\u00fablico, o tributo \u00e9 o PASEP (Programa de Forma\u00e7\u00e3o do Patrim\u00f4nio do Servidor P\u00fablico). O tributo tamb\u00e9m vem especificado sobre as notas fiscais emitidas.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;ISS&quot;}\">ISS<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;O Imposto sobre Servi\u00e7os (ISS) incide sobre a presta\u00e7\u00e3o de servi\u00e7os, seja de empresas ou profissionais aut\u00f4nomos. Trata-se de um imposto municipal e, portanto, sua al\u00edquota varia de acordo com a regra de cada cidade. De toda forma, o valor sempre ficar\u00e1 entre 2% e 5% sobre o valor total do servi\u00e7o.\\n\\nVamos supor, ent\u00e3o, que a cidade para a qual voc\u00ea prestou servi\u00e7o tem al\u00edquota definida de 5%, e o servi\u00e7o total foi de R$ 5 mil. Isso significa que o ISS ser\u00e1 de 250 reais.&quot;}\">O Imposto sobre Servi\u00e7os (ISS) incide sobre a presta\u00e7\u00e3o de servi\u00e7os, seja de empresas ou profissionais aut\u00f4nomos. Trata-se de um imposto municipal e, portanto, sua al\u00edquota varia de acordo com a regra de cada cidade. De toda forma, o valor sempre ficar\u00e1 entre 2% e 5% sobre o valor total do servi\u00e7o.<\/p>\n<p>Vamos supor, ent\u00e3o, que a cidade para a qual voc\u00ea prestou servi\u00e7o tem al\u00edquota definida de 5%, e o servi\u00e7o total foi de R$ 5 mil. Isso significa que o ISS ser\u00e1 de 250 reais.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;ICMS&quot;}\">ICMS<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Enquanto o ISS envolve a presta\u00e7\u00e3o de servi\u00e7os, o Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Presta\u00e7\u00e3o de Servi\u00e7os (ICMS) est\u00e1 mais relacionado \u00e0s mercadorias vendidas. Neste caso, a al\u00edquota tamb\u00e9m varia, uma vez que se trata de um imposto estadual sobre a nota. A diferen\u00e7a \u00e9 que quem define \u00e9 o estado e n\u00e3o o munic\u00edpio.\\n\\nTodas as movimenta\u00e7\u00f5es de produtos, assim como servi\u00e7os como comunica\u00e7\u00e3o e transporte, envolvem o tributo do ICMS, que geralmente tem uma al\u00edquota de 17% ou 18%. Consulte a al\u00edquota em seu estado e\u00a0multiplique o pre\u00e7o do produto para chegar ao total do ICMS.&quot;}\">Enquanto o ISS envolve a presta\u00e7\u00e3o de servi\u00e7os, o Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Presta\u00e7\u00e3o de Servi\u00e7os (ICMS) est\u00e1 mais relacionado \u00e0s mercadorias vendidas. Neste caso, a al\u00edquota tamb\u00e9m varia, uma vez que se trata de um imposto estadual sobre a nota. A diferen\u00e7a \u00e9 que quem define \u00e9 o estado e n\u00e3o o munic\u00edpio.<\/p>\n<p>Todas as movimenta\u00e7\u00f5es de produtos, assim como servi\u00e7os como comunica\u00e7\u00e3o e transporte, envolvem o tributo do ICMS, que geralmente tem uma al\u00edquota de 17% ou 18%. Consulte a al\u00edquota em seu estado e\u00a0<a href=\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-csll\/\">multiplique o pre\u00e7o do produto<\/a> para chegar ao total do ICMS.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;IPI&quot;}\">IPI<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;O Imposto sobre Produto Industrializado (IPI) incide sobre produtos industrializados e sua al\u00edquota chega a 30%. Ser\u00e1 cobrado somente quando houver uma opera\u00e7\u00e3o que modificou o produto original.\\n\\nCaso a mat\u00e9ria-prima n\u00e3o tenha tido nenhuma mudan\u00e7a desde sua fabrica\u00e7\u00e3o, n\u00e3o ser\u00e1 necess\u00e1rio.\\n\\nAinda existem outros dois impostos sob produtos, o de Importa\u00e7\u00e3o (II) e Exporta\u00e7\u00e3o (IE) \u2013 o primeiro sobre as notas de produtos importados vendidos no Brasil, e o segundo de produtos que saem do Brasil e v\u00e3o para fora.&quot;}\">O Imposto sobre Produto Industrializado (IPI) incide sobre produtos industrializados e sua al\u00edquota chega a 30%. Ser\u00e1 cobrado somente quando houver uma opera\u00e7\u00e3o que modificou o produto original.<\/p>\n<p>Caso a mat\u00e9ria-prima n\u00e3o tenha tido nenhuma mudan\u00e7a desde sua fabrica\u00e7\u00e3o, n\u00e3o ser\u00e1 necess\u00e1rio.<\/p>\n<p>Ainda existem outros dois impostos sob produtos, o de Importa\u00e7\u00e3o (II) e Exporta\u00e7\u00e3o (IE) \u2013 o primeiro sobre as notas de produtos importados vendidos no Brasil, e o segundo de produtos que saem do Brasil e v\u00e3o para fora.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Existem algumas particularidades de impostos nas notas fiscais para quem \u00e9 optante do Lucro Presumido. Ensinamos como calcular aqui:\u00a0<a href=\"https:\/\/nfe.io\/blog\/nota-fiscal\/impostos-nota-fiscal-de-servicos-lucro-presumido\/\">Quais s\u00e3o os impostos na nota fiscal de servi\u00e7os Lucro Presumido? Veja todos eles e como calcular!<\/a><\/p>\n<p>Outro tipo de empres\u00e1rios que n\u00e3o citamos, mas que ainda assim pagam impostos, s\u00e3o os Microempreendedores Individuais (MEIs). Acontece que, diferentemente de empresas do Lucro Real, Presumido ou Simples Nacional, os cadastrados no MEI pagam todos seus impostos em um \u00fanico documento, o DAS (Documento de Arrecada\u00e7\u00e3o do Simples Nacional).<\/p>\n<p>Por cerca de R$ 52 mensais, o microempreendedor j\u00e1 est\u00e1 contribuindo INSS, ICMS e ISS. A emiss\u00e3o de notas fiscais, neste caso, n\u00e3o \u00e9 cobrada.<\/p>\n<p>E ent\u00e3o, j\u00e1 sabe como calcular os impostos de uma empresa? Precisa de ajuda com algum tributo espec\u00edfico? Deixe seu coment\u00e1rio para que possamos te ajudar!<\/p>\n<p><strong>Veja tamb\u00e9m quais impostos diretos incidem sobre as empresas ao emitir uma nota fiscal de servi\u00e7os:<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7409 size-large\" src=\"https:\/\/nfe.io\/blog\/app\/uploads\/2017\/09\/calculo-de-impostos-nota-fiscal-de-servicos-698x1024.png\" alt=\"Para que serve a Nota Fiscal\" width=\"698\" height=\"1024\" srcset=\"https:\/\/nfe.io\/blog\/app\/uploads\/2017\/09\/calculo-de-impostos-nota-fiscal-de-servicos-698x1024.png 698w, https:\/\/nfe.io\/blog\/app\/uploads\/2017\/09\/calculo-de-impostos-nota-fiscal-de-servicos-205x300.png 205w, https:\/\/nfe.io\/blog\/app\/uploads\/2017\/09\/calculo-de-impostos-nota-fiscal-de-servicos-768x1126.png 768w, https:\/\/nfe.io\/blog\/app\/uploads\/2017\/09\/calculo-de-impostos-nota-fiscal-de-servicos-680x997.png 680w, https:\/\/nfe.io\/blog\/app\/uploads\/2017\/09\/calculo-de-impostos-nota-fiscal-de-servicos-500x733.png 500w, https:\/\/nfe.io\/blog\/app\/uploads\/2017\/09\/calculo-de-impostos-nota-fiscal-de-servicos-400x587.png 400w, https:\/\/nfe.io\/blog\/app\/uploads\/2017\/09\/calculo-de-impostos-nota-fiscal-de-servicos-200x293.png 200w, https:\/\/nfe.io\/blog\/app\/uploads\/2017\/09\/calculo-de-impostos-nota-fiscal-de-servicos-50x73.png 50w, https:\/\/nfe.io\/blog\/app\/uploads\/2017\/09\/calculo-de-impostos-nota-fiscal-de-servicos.png 800w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><\/p>\n<h2>Um gerenciador de notas fiscais faz c\u00e1lculo autom\u00e1tico dos impostos!<\/h2>\n<p>Usando uma software como o<span style=\"font-weight: 400;\">\u00a0<\/span><a href=\"https:\/\/nfe.io\/\"><span style=\"font-weight: 400;\">NFE.io<\/span><\/a><span style=\"font-weight: 400;\">\u00a0o c\u00e1lculo dos impostos \u00e9 autom\u00e1tico. Al\u00e9m disso, ele emite e gera os arquivos XML e HTML, que s\u00e3o enviado\u00a0 por e-mail aos clientes.<\/span><\/p>\n<p>Outra vantagem? Voc\u00ea tem\u00a0<strong><a href=\"http:\/\/p.nfe.io\/certificado-digital-25off\/\">desconto na emiss\u00e3o do certificado digital<\/a><\/strong>.<\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot; \n\n\t&lt;div class=&quot;cta-blog green io&quot; id=&quot;6142&quot;&gt;\n\n\t\t&lt;div class=&quot;cta-title&quot;&gt;\n\t\t\t&lt;h3&gt; &lt;\/h3&gt;\n\t\t&lt;\/div&gt;\n\n\t\t&lt;div class=&quot;cta-content&quot;&gt;\n\t\t\t&lt;p&gt;&lt;\/p&gt;\n\t\t&lt;\/div&gt;\n\n\t\t&lt;div class=&quot;cta-area&quot;&gt;\n\n\t\t\t&lt;!-- &lt;div class=&quot;left&quot;&gt;\n\t\t\t\t&lt;h5&gt;&lt;\/h5&gt;\n\t\t\t\t&lt;div id=&quot;subtitle&quot;&gt;&lt;\/div&gt;\n\t\t\t&lt;\/div&gt; --&gt;\n\n\t\t\t&lt;!-- &lt;div class=&quot;right&quot;&gt; --&gt;\n\t\t\t\t\t\t\t&lt;!-- &lt;\/div&gt; --&gt;\n\n\t\t&lt;\/div&gt;\n\n\t&lt;\/div&gt;\n\n\t&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:961,&quot;3&quot;:{&quot;1&quot;:0},&quot;9&quot;:1,&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea gostaria de entender melhor como calcular impostos de uma empresa, mas ainda n\u00e3o sabe como? Normalmente, as notas fiscais especificam os impostos&#8230;<\/p>\n","protected":false},"author":2,"featured_media":6147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-6142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-financeiro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como calcular os impostos de uma empresa: guia pr\u00e1tico<\/title>\n<meta name=\"description\" content=\"Veja como planejamento tribut\u00e1rio e o entendimento dos principais impostos pode te ajudar a saber como calcular os impostos de uma empresa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como calcular os impostos de uma empresa: guia pr\u00e1tico\" \/>\n<meta property=\"og:description\" content=\"Veja como planejamento tribut\u00e1rio e o entendimento dos principais impostos pode te ajudar a saber como calcular os impostos de uma empresa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/\" \/>\n<meta property=\"og:site_name\" content=\"NFE.io Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nfe.io\" \/>\n<meta property=\"article:author\" content=\"https:\/\/fb.com\/gblmarquez\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-08T08:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-02T15:29:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/03\/como-calcular-impostos-empresa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"669\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriel Marquez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gblmarquez\" \/>\n<meta name=\"twitter:site\" content=\"@nfe_io\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Marquez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/\"},\"author\":{\"name\":\"Gabriel Marquez\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/5dba936eb6ef9ce2b7cd1bf6fb7aad11\"},\"headline\":\"Quais impostos uma empresa paga? Saiba de uma vez por todas como calcular os impostos de uma empresa\",\"datePublished\":\"2019-03-08T08:00:27+00:00\",\"dateModified\":\"2022-03-02T15:29:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/\"},\"wordCount\":1224,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nfe.io\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/03\/como-calcular-impostos-empresa.jpg\",\"articleSection\":[\"Gest\u00e3o Financeira\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/\",\"url\":\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/\",\"name\":\"Como calcular os impostos de uma empresa: guia pr\u00e1tico\",\"isPartOf\":{\"@id\":\"https:\/\/nfe.io\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/03\/como-calcular-impostos-empresa.jpg\",\"datePublished\":\"2019-03-08T08:00:27+00:00\",\"dateModified\":\"2022-03-02T15:29:10+00:00\",\"description\":\"Veja como planejamento tribut\u00e1rio e o entendimento dos principais impostos pode te ajudar a saber como calcular os impostos de uma empresa.\",\"breadcrumb\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#primaryimage\",\"url\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/03\/como-calcular-impostos-empresa.jpg\",\"contentUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/03\/como-calcular-impostos-empresa.jpg\",\"width\":800,\"height\":669,\"caption\":\"como calcular os impostos de uma empresa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nfe.io\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quais impostos uma empresa paga? Saiba de uma vez por todas como calcular os impostos de uma empresa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nfe.io\/blog\/#website\",\"url\":\"https:\/\/nfe.io\/blog\/\",\"name\":\"NFE.io Blog\",\"description\":\"Automatize Suas Obriga\u00e7\u00f5es Fiscais com Efici\u00eancia\",\"publisher\":{\"@id\":\"https:\/\/nfe.io\/blog\/#organization\"},\"alternateName\":\"NFE.io\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nfe.io\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nfe.io\/blog\/#organization\",\"name\":\"NFE io\",\"alternateName\":\"NFE\",\"url\":\"https:\/\/nfe.io\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png\",\"contentUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png\",\"width\":143,\"height\":41,\"caption\":\"NFE io\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nfe.io\",\"https:\/\/x.com\/nfe_io\",\"https:\/\/github.com\/nfe\",\"https:\/\/www.linkedin.com\/company\/10407705\/\",\"https:\/\/www.youtube.com\/channel\/UCB1PFw8rxeIN64k_t5FWEAQ\",\"https:\/\/www.instagram.com\/nfe.io\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/5dba936eb6ef9ce2b7cd1bf6fb7aad11\",\"name\":\"Gabriel Marquez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b9c35eac9573908c93a925466c8998ae2075037e3ccc57d03dea6faba89907ba?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b9c35eac9573908c93a925466c8998ae2075037e3ccc57d03dea6faba89907ba?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Gabriel Marquez\"},\"description\":\"Empreendedor e Fundador da NFE.io e outras startups. Focado em ajudar empreendedores a escalar seus neg\u00f3cios. Interessado? Marque um papo!\",\"sameAs\":[\"https:\/\/nfe.io\",\"https:\/\/fb.com\/gblmarquez\",\"https:\/\/br.linkedin.com\/in\/gblmarquez\",\"https:\/\/x.com\/gblmarquez\"],\"url\":\"https:\/\/nfe.io\/blog\/author\/gabrielmarquez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como calcular os impostos de uma empresa: guia pr\u00e1tico","description":"Veja como planejamento tribut\u00e1rio e o entendimento dos principais impostos pode te ajudar a saber como calcular os impostos de uma empresa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/","og_locale":"en_US","og_type":"article","og_title":"Como calcular os impostos de uma empresa: guia pr\u00e1tico","og_description":"Veja como planejamento tribut\u00e1rio e o entendimento dos principais impostos pode te ajudar a saber como calcular os impostos de uma empresa.","og_url":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/","og_site_name":"NFE.io Blog","article_publisher":"https:\/\/www.facebook.com\/nfe.io","article_author":"https:\/\/fb.com\/gblmarquez","article_published_time":"2019-03-08T08:00:27+00:00","article_modified_time":"2022-03-02T15:29:10+00:00","og_image":[{"width":800,"height":669,"url":"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/03\/como-calcular-impostos-empresa.jpg","type":"image\/jpeg"}],"author":"Gabriel Marquez","twitter_card":"summary_large_image","twitter_creator":"@gblmarquez","twitter_site":"@nfe_io","twitter_misc":{"Written by":"Gabriel Marquez","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#article","isPartOf":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/"},"author":{"name":"Gabriel Marquez","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/5dba936eb6ef9ce2b7cd1bf6fb7aad11"},"headline":"Quais impostos uma empresa paga? Saiba de uma vez por todas como calcular os impostos de uma empresa","datePublished":"2019-03-08T08:00:27+00:00","dateModified":"2022-03-02T15:29:10+00:00","mainEntityOfPage":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/"},"wordCount":1224,"commentCount":0,"publisher":{"@id":"https:\/\/nfe.io\/blog\/#organization"},"image":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#primaryimage"},"thumbnailUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/03\/como-calcular-impostos-empresa.jpg","articleSection":["Gest\u00e3o Financeira"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/","url":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/","name":"Como calcular os impostos de uma empresa: guia pr\u00e1tico","isPartOf":{"@id":"https:\/\/nfe.io\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#primaryimage"},"image":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#primaryimage"},"thumbnailUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/03\/como-calcular-impostos-empresa.jpg","datePublished":"2019-03-08T08:00:27+00:00","dateModified":"2022-03-02T15:29:10+00:00","description":"Veja como planejamento tribut\u00e1rio e o entendimento dos principais impostos pode te ajudar a saber como calcular os impostos de uma empresa.","breadcrumb":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#primaryimage","url":"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/03\/como-calcular-impostos-empresa.jpg","contentUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2019\/03\/como-calcular-impostos-empresa.jpg","width":800,"height":669,"caption":"como calcular os impostos de uma empresa"},{"@type":"BreadcrumbList","@id":"https:\/\/nfe.io\/blog\/financeiro\/quais-impostos-uma-empresa-paga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nfe.io\/blog\/"},{"@type":"ListItem","position":2,"name":"Quais impostos uma empresa paga? Saiba de uma vez por todas como calcular os impostos de uma empresa"}]},{"@type":"WebSite","@id":"https:\/\/nfe.io\/blog\/#website","url":"https:\/\/nfe.io\/blog\/","name":"NFE.io Blog","description":"Automatize Suas Obriga\u00e7\u00f5es Fiscais com Efici\u00eancia","publisher":{"@id":"https:\/\/nfe.io\/blog\/#organization"},"alternateName":"NFE.io","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nfe.io\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nfe.io\/blog\/#organization","name":"NFE io","alternateName":"NFE","url":"https:\/\/nfe.io\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png","contentUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png","width":143,"height":41,"caption":"NFE io"},"image":{"@id":"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nfe.io","https:\/\/x.com\/nfe_io","https:\/\/github.com\/nfe","https:\/\/www.linkedin.com\/company\/10407705\/","https:\/\/www.youtube.com\/channel\/UCB1PFw8rxeIN64k_t5FWEAQ","https:\/\/www.instagram.com\/nfe.io\/"]},{"@type":"Person","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/5dba936eb6ef9ce2b7cd1bf6fb7aad11","name":"Gabriel Marquez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b9c35eac9573908c93a925466c8998ae2075037e3ccc57d03dea6faba89907ba?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b9c35eac9573908c93a925466c8998ae2075037e3ccc57d03dea6faba89907ba?s=96&d=wp_user_avatar&r=g","caption":"Gabriel Marquez"},"description":"Empreendedor e Fundador da NFE.io e outras startups. Focado em ajudar empreendedores a escalar seus neg\u00f3cios. Interessado? Marque um papo!","sameAs":["https:\/\/nfe.io","https:\/\/fb.com\/gblmarquez","https:\/\/br.linkedin.com\/in\/gblmarquez","https:\/\/x.com\/gblmarquez"],"url":"https:\/\/nfe.io\/blog\/author\/gabrielmarquez\/"}]}},"_links":{"self":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts\/6142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/comments?post=6142"}],"version-history":[{"count":0,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts\/6142\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/media\/6147"}],"wp:attachment":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/media?parent=6142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/categories?post=6142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/tags?post=6142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}