{"id":12279,"date":"2024-06-20T12:06:34","date_gmt":"2024-06-20T15:06:34","guid":{"rendered":"https:\/\/nfe.io\/blog\/?p=12279"},"modified":"2024-06-21T09:29:58","modified_gmt":"2024-06-21T12:29:58","slug":"impostos-mei-profissionais-liberais","status":"publish","type":"post","link":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/","title":{"rendered":"Quais s\u00e3o os impostos para MEIs e profissionais liberais?"},"content":{"rendered":"<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Em 2021, o Brasil bateu o recorde de aberturas de novos neg\u00f3cios no pa\u00eds desde 2010: segundo os <\/span><a class=\"ql-font-huge\" href=\"https:\/\/www.serasaexperian.com.br\/sala-de-imprensa\/analise-de-dados\/com-mais-de-300-mil-novos-negocios-brasil-bate-recorde-historico-de-abertura-de-meis-revela-serasa-experian\/\" rel=\"noopener noreferrer\" data-action=\"interacted\" data-object=\"content\" data-ui-action=\"clicked\" data-ui-object=\"link\" data-ui-object-detail=\"dados mais recentes do SEBRAE\" data-ui-access-point=\"\" data-sku=\"\" data-wa-link=\"\" data-object-detail=\"\">dados mais recentes do SEBRAE<\/a><span class=\"ql-font-huge\">, durante o m\u00eas de janeiro daquele ano foram abertos 312.462 novos registros de microempreendedores individuais (MEIs).<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">O aumento do n\u00famero de MEIs \u00e9, al\u00e9m de um reflexo da pandemia, um indicativo de que cada vez mais pessoas t\u00eam buscado <\/span>empreender<span class=\"ql-font-huge\"> ou formalizar neg\u00f3cios j\u00e1 existentes. <\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Mas, mesmo com esse aumento, ainda existem muitas d\u00favidas sobre essa modalidade, suas vantagens e at\u00e9 mesmo sobre o imposto para MEI.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Para responder todas as perguntas sobre o que \u00e9 ser microempreendedor individual, as vantagens de se enquadrar nessa modalidade e tributos que devem ser pagos, n\u00f3s do NFE.io c<\/span><span class=\"ql-font-huge\">riamos esse artigo.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Continue a ler e saiba tudo o que \u00e9 necess\u00e1rio sobre ser um microempreendedor individual!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"ql-align-justify\"><span class=\"ql-font-heading02\">O que \u00e9 MEI?<\/span><\/h2>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">O MEI <\/span><span class=\"ql-font-huge\">\u2014<\/span><span class=\"ql-font-huge\"> sigla para microempreendedor individual <\/span><span class=\"ql-font-huge\">\u2014<\/span><span class=\"ql-font-huge\"> \u00e9 um enquadramento empresarial feito para formalizar as atividades de <\/span>trabalhadores aut\u00f4nomos<span class=\"ql-font-huge\">.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Ao se tornar microempreendedor individual, o trabalhador se torna uma pessoa jur\u00eddica, passa a ter um CNPJ e poder\u00e1 operar com ele.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Criado ap\u00f3s a altera\u00e7\u00e3o do <\/span><a class=\"ql-font-huge\" href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/lcp\/lcp123.htm\" rel=\"noopener noreferrer\" data-action=\"interacted\" data-object=\"content\" data-ui-action=\"clicked\" data-ui-object=\"link\" data-ui-object-detail=\"Estatuto Nacional da Microempresa e Empresa de Pequeno Porte\" data-ui-access-point=\"\" data-sku=\"\" data-wa-link=\"\" data-object-detail=\"\">Estatuto Nacional da Microempresa e Empresa de Pequeno Porte<\/a><span class=\"ql-font-huge\">, em 2008, a abertura do MEI \u00e9 facilitada e permite que o profissional possa emitir notas fiscais e abrir conta jur\u00eddica no banco. <\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">O microempreendedor individual at\u00e9 mesmo conta com um regime tribut\u00e1rio diferenciado para pagamento de impostos: o <\/span>Simples Nacional<span class=\"ql-font-huge\">.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Por\u00e9m, para se tornar MEI, \u00e9 necess\u00e1rio atender a alguns requisitos.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">O primeiro \u00e9 faturar, no m\u00e1ximo, at\u00e9 R$ 81 mil por ano. <\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">MEIs tamb\u00e9m n\u00e3o podem contratar mais do que um \u00fanico funcion\u00e1rio e n\u00e3o podem ter s\u00f3cios ou ser s\u00f3cios de outra empresa j\u00e1 aberta.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Al\u00e9m disso, quem exerce atividade intelectual n\u00e3o pode ser microempreendedor individual. <\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Esse \u00e9 o caso de m\u00e9dicos, dentistas, advogados, engenheiros e psic\u00f3logos: esses profissionais s\u00e3o considerados profissionais liberais e devem ser registrados em suas respectivas ordens ou conselhos profissionais.\u00a0<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Como voc\u00ea ver\u00e1 nos pr\u00f3ximos t\u00f3picos, o imposto do MEI e de profissionais liberais s\u00e3o diferentes.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"ql-align-justify\"><span class=\"ql-font-heading02\">Quais as vantagens de se tornar um MEI?<\/span><\/h2>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">A formaliza\u00e7\u00e3o como microempreendedor individual garante uma s\u00e9rie de vantagens ao trabalhador.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Al\u00e9m de se encaixar em um <\/span>regime tribut\u00e1rio<span class=\"ql-font-huge\"> diferenciado, conseguir emitir notas fiscais e poder abrir uma conta banc\u00e1ria jur\u00eddica, se tornar MEI tamb\u00e9m garante o acesso a <\/span>servi\u00e7os banc\u00e1rios<span class=\"ql-font-huge\"> exclusivos para empresas e a prioridade em licita\u00e7\u00f5es do governo.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Mas as vantagens que mais chamam aten\u00e7\u00e3o quando falamos sobre essa modalidade s\u00e3o seus direitos e o valor dos impostos. Vamos falar sobre esses assuntos nos t\u00f3picos a seguir.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"ql-align-justify\"><span class=\"ql-font-heading02\">Quais s\u00e3o os direitos do MEI?<\/span><\/h2>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Mesmo tendo um CNPJ e n\u00e3o possuindo carteira assinada, o microempreendedor individual tamb\u00e9m tem direito a benef\u00edcios previdenci\u00e1rios.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Ao se tornar MEI, o trabalhador passa a ter direito \u00e0 aposentadoria por idade ou por invalidez, aux\u00edlio-doen\u00e7a e aux\u00edlio-maternidade. <\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">No caso de morte, os familiares tamb\u00e9m t\u00eam direito a pens\u00e3o.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Mas, para garantir esses direitos, \u00e9 necess\u00e1rio realizar o pagamento do imposto do MEI <\/span><span class=\"ql-font-huge\">\u2014<\/span><span class=\"ql-font-huge\"> que \u00e9 outra vantagem, como voc\u00ea ver\u00e1 agora.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"ql-align-justify\"><span class=\"ql-font-heading02\">Qual imposto o MEI deve pagar?<\/span><\/h2>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Como falamos anteriormente, MEIs s\u00e3o enquadrados em um regime tribut\u00e1rio diferenciado, o Simples Nacional. E \u00e9 atrav\u00e9s desse regime tribut\u00e1rio que s\u00e3o cobrados os impostos pagos pelo microempreendedor individual.<\/span><\/p>\n<p class=\"ql-align-justify\"><a class=\"ql-font-huge\" href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/lcp\/lcp123.htm\" rel=\"noopener noreferrer\" data-action=\"interacted\" data-object=\"content\" data-ui-action=\"clicked\" data-ui-object=\"link\" data-ui-object-detail=\"Criado em 2006\" data-ui-access-point=\"\" data-sku=\"\" data-wa-link=\"\" data-object-detail=\"\">Criado em 2006<\/a><span class=\"ql-font-huge\">, o Simples Nacional \u00e9 um regime simplificado de arrecada\u00e7\u00e3o de tributos: ele re\u00fane diversos impostos para serem pagos de uma s\u00f3 vez, em uma mesma guia, chamada de DAS <\/span><span class=\"ql-font-huge\">\u2014<\/span><span class=\"ql-font-huge\"> o Documento de Arrecada\u00e7\u00e3o do Simples Nacional.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">O mais interessante em rela\u00e7\u00e3o ao DAS \u00e9 que o valor do imposto a ser pago mensalmente <\/span><span class=\"ql-font-huge\">\u2014<\/span><span class=\"ql-font-huge\"> calculado conforme o sal\u00e1rio m\u00ednimo <\/span><span class=\"ql-font-huge\">\u2014<\/span><span class=\"ql-font-huge\"> \u00e9 fixo, ou seja, n\u00e3o h\u00e1 altera\u00e7\u00e3o de valor com o passar dos meses, independentemente do <\/span>faturamento do MEI<span class=\"ql-font-huge\">.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Ou seja, quando falamos sobre valor de imposto do MEI ou o pagamento de tributos sendo um microempreendedor individual, estamos falando sobre o valor fixo da DAS.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"ql-align-justify\"><span class=\"ql-font-heading02\">Quais impostos fazem parte da DAS?<\/span><\/h2>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">A principal vantagem da DAS \u00e9 a possibilidade de realizar o pagamento de diversos impostos em uma \u00fanica guia, o que facilita o dia a dia de qualquer empreendedor.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Os impostos que fazem <\/span>parte da DAS<span class=\"ql-font-huge\"> s\u00e3o os seguintes:<\/span><\/p>\n<ul>\n<li class=\"ql-align-justify\"><span class=\"ql-font-huge\">Imposto de Renda de Pessoa Jur\u00eddica (IRPJ).<\/span><\/li>\n<li class=\"ql-align-justify\"><span class=\"ql-font-huge\">Imposto sobre Produtos Industrializados (IPI).<\/span><\/li>\n<li class=\"ql-align-justify\"><span class=\"ql-font-huge\">Contribui\u00e7\u00e3o Social sobre Lucro L\u00edquido (CSLL).<\/span><\/li>\n<li class=\"ql-align-justify\"><span class=\"ql-font-huge\">Contribui\u00e7\u00e3o para o Financiamento da Seguridade Social (Cofins).<\/span><\/li>\n<li class=\"ql-align-justify\"><span class=\"ql-font-huge\">Programa de Integra\u00e7\u00e3o Social (PIS).<\/span><\/li>\n<li class=\"ql-align-justify\"><span class=\"ql-font-huge\">Contribui\u00e7\u00e3o Patronal Previdenci\u00e1ria (CPP).<\/span><\/li>\n<li class=\"ql-align-justify\"><span class=\"ql-font-huge\">Imposto sobre a Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os (ICMS).<\/span><\/li>\n<li class=\"ql-align-justify\"><span class=\"ql-font-huge\">Imposto sobre Servi\u00e7os (ISS).<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2 class=\"ql-align-justify\"><span class=\"ql-font-heading02\">Qual o valor da DAS?<\/span><\/h2>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Em 2022, com o reajuste do sal\u00e1rio m\u00ednimo para R$ 1.212,00, houve tamb\u00e9m o reajuste do valor dos impostos pagos pelos microempreendedores individuais e outros optantes do Simples Nacional.<\/span><\/p>\n<p class=\"ql-align-justify\"><a class=\"ql-font-huge\" href=\"https:\/\/www.cnnbrasil.com.br\/business\/contribuicao-do-mei-passa-a-ter-novo-valor-a-partir-de-fevereiro\/#:~:text=O%20DAS%20tem%20custo%20fixo,se%20for%20com%C3%A9rcio%20ou%20ind%C3%BAstria.\" rel=\"noopener noreferrer\" data-action=\"interacted\" data-object=\"content\" data-ui-action=\"clicked\" data-ui-object=\"link\" data-ui-object-detail=\"Desde fevereiro de 2022\" data-ui-access-point=\"\" data-sku=\"\" data-wa-link=\"\" data-object-detail=\"\">Desde fevereiro de 2022<\/a><span class=\"ql-font-huge\">, o valor referente ao INSS na DAS passa a ser de R$ 60,60. Esse valor corresponde a 5% do sal\u00e1rio m\u00ednimo, base de c\u00e1lculo dos impostos.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Al\u00e9m disso, MEIs que exercem atividades ligadas a servi\u00e7os pagam tamb\u00e9m o valor fixo de R$ 5,00 de <\/span>Imposto sobre Servi\u00e7os<span class=\"ql-font-huge\"> (ISS), e os microempreendedores individuais que exercem atividades ligadas ao com\u00e9rcio e \u00e0 ind\u00fastria, pagam o valor fixo de R$ 1,00 referente ao <\/span>Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os<span class=\"ql-font-huge\"> (ICMS).<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Para consultar qual o valor a ser pago mensalmente, basta consultar e emitir a DAS no Portal do Simples Nacional.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"ql-align-justify\"><span class=\"ql-font-heading02\">Qual imposto os profissionais liberais devem pagar?<\/span><\/h2>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Para profissionais liberais, a quest\u00e3o do pagamento de impostos \u00e9 um pouco diferente, j\u00e1 que n\u00e3o existe uma guia \u00fanica para pagamento.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Por\u00e9m, isso n\u00e3o significa que eles n\u00e3o tenham que pagar alguns impostos iguais aos pagos pelos MEIs.\u00a0<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Os impostos que devem ser pagos por profissionais liberais s\u00e3o os seguintes:<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"ql-align-justify\"><strong class=\"ql-font-heading03\">1. INSS<\/strong><\/h3>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">A contribui\u00e7\u00e3o para a Previd\u00eancia Social pode ser feita de duas formas: o pagamento de 11% sobre o valor do sal\u00e1rio m\u00ednimo ou 20% sobre os rendimentos recebidos no m\u00eas.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Para MEIs, a Contribui\u00e7\u00e3o Patronal Previdenci\u00e1ria \u00e9 o equivalente ao INSS.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"ql-align-justify\"><strong class=\"ql-font-heading03\">2. Imposto de Renda (IR)<\/strong><\/h3>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Seja como pessoa f\u00edsica ou como pessoa jur\u00eddica, o profissional liberal deve realizar o pagamento do IR quando fizer a Declara\u00e7\u00e3o do Imposto de Renda.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"ql-align-justify\"><strong class=\"ql-font-heading03\">3. Imposto sobre Servi\u00e7os (ISS)<\/strong><\/h3>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">No caso de profissionais liberais, o ISS varia de acordo com o munic\u00edpio. Por isso, \u00e9 preciso consultar a prefeitura da cidade onde os servi\u00e7os s\u00e3o exercidos para saber qual o valor a ser pago neste imposto.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"ql-align-justify\"><strong class=\"ql-font-heading03\">4. Anuidade de Conselhos<\/strong><\/h3>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Profissionais liberais devem estar registrados em conselhos profissionais de suas respectivas classes e, por isso, precisam pagar a anuidade para esses conselhos.<\/span><\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Esse pagamento \u00e9 uma das garantias de que o n\u00famero de registro estar\u00e1 ativo e ele poder\u00e1 atuar como profissional liberal.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ql-align-justify\"><span class=\"ql-font-huge\">Lembre-se: seja como microempreendedor individual ou como profissional liberal, \u00e9 fundamental ter controle das finan\u00e7as do seu neg\u00f3cio.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Esse conte\u00fado foi \u00fatil para voc\u00ea? Inscreva-se em nossa newsletter e receba mais conte\u00fado exclusivo diretamente na sua caixa de entrada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em 2021, o Brasil bateu o recorde de aberturas de novos neg\u00f3cios no pa\u00eds desde 2010: segundo os dados mais recentes do SEBRAE,&#8230;<\/p>\n","protected":false},"author":23,"featured_media":12280,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-12279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-financeiro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quais s\u00e3o os impostos para MEIs e profissionais liberais? - NFE.io Blog<\/title>\n<meta name=\"description\" content=\"Neste artigo voc\u00ea vai aprender sobre os principais impostos e obriga\u00e7\u00f5es do MEI e dos profissionais liberais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quais s\u00e3o os impostos para MEIs e profissionais liberais? - NFE.io Blog\" \/>\n<meta property=\"og:description\" content=\"Neste artigo voc\u00ea vai aprender sobre os principais impostos e obriga\u00e7\u00f5es do MEI e dos profissionais liberais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/\" \/>\n<meta property=\"og:site_name\" content=\"NFE.io Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nfe.io\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/francisco.j.felinto\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-20T15:06:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-21T12:29:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/quais-sao-os-impostos-para-meis-e-profissionais-liberais.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Felinto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nfe_io\" \/>\n<meta name=\"twitter:site\" content=\"@nfe_io\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Felinto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/\"},\"author\":{\"name\":\"Francisco Felinto\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/2eaaaa06c00fec05b47e7003dae7ed65\"},\"headline\":\"Quais s\u00e3o os impostos para MEIs e profissionais liberais?\",\"datePublished\":\"2024-06-20T15:06:34+00:00\",\"dateModified\":\"2024-06-21T12:29:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/\"},\"wordCount\":1237,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nfe.io\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/quais-sao-os-impostos-para-meis-e-profissionais-liberais.jpg\",\"articleSection\":[\"Gest\u00e3o Financeira\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/\",\"url\":\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/\",\"name\":\"Quais s\u00e3o os impostos para MEIs e profissionais liberais? - NFE.io Blog\",\"isPartOf\":{\"@id\":\"https:\/\/nfe.io\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/quais-sao-os-impostos-para-meis-e-profissionais-liberais.jpg\",\"datePublished\":\"2024-06-20T15:06:34+00:00\",\"dateModified\":\"2024-06-21T12:29:58+00:00\",\"description\":\"Neste artigo voc\u00ea vai aprender sobre os principais impostos e obriga\u00e7\u00f5es do MEI e dos profissionais liberais.\",\"breadcrumb\":{\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#primaryimage\",\"url\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/quais-sao-os-impostos-para-meis-e-profissionais-liberais.jpg\",\"contentUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/quais-sao-os-impostos-para-meis-e-profissionais-liberais.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nfe.io\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quais s\u00e3o os impostos para MEIs e profissionais liberais?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nfe.io\/blog\/#website\",\"url\":\"https:\/\/nfe.io\/blog\/\",\"name\":\"NFE.io Blog\",\"description\":\"Automatize Suas Obriga\u00e7\u00f5es Fiscais com Efici\u00eancia\",\"publisher\":{\"@id\":\"https:\/\/nfe.io\/blog\/#organization\"},\"alternateName\":\"NFE.io\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nfe.io\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nfe.io\/blog\/#organization\",\"name\":\"NFE io\",\"alternateName\":\"NFE\",\"url\":\"https:\/\/nfe.io\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png\",\"contentUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png\",\"width\":143,\"height\":41,\"caption\":\"NFE io\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nfe.io\",\"https:\/\/x.com\/nfe_io\",\"https:\/\/github.com\/nfe\",\"https:\/\/www.linkedin.com\/company\/10407705\/\",\"https:\/\/www.youtube.com\/channel\/UCB1PFw8rxeIN64k_t5FWEAQ\",\"https:\/\/www.instagram.com\/nfe.io\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/2eaaaa06c00fec05b47e7003dae7ed65\",\"name\":\"Francisco Felinto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/be0f81adb0794281ac9b3ffc87137ad2bf518c3d8bc98e1fbc6526bfc850433d?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/be0f81adb0794281ac9b3ffc87137ad2bf518c3d8bc98e1fbc6526bfc850433d?s=96&r=g\",\"caption\":\"Francisco Felinto\"},\"description\":\"S\u00f3cio e CECO - Chief Ecosystem Officer na NFE.io, Mestre em Tecnologia da Informa\u00e7\u00e3o Aplicada, MBI em Gest\u00e3o da Informa\u00e7\u00e3o e Especializa\u00e7\u00e3o em Gest\u00e3o de Projeto integrado ao PMI. Professor Universit\u00e1rio e Ex Diretor da Fatec Osasco (2018-22). Fundador do programa Descodificadas, vice-presidente do Instituto Arte das Na\u00e7\u00f5es e Atuante na UWC - Brasil.\",\"sameAs\":[\"https:\/\/www.facebook.com\/francisco.j.felinto\/\",\"https:\/\/www.instagram.com\/francisco.felinto.jr\/\",\"https:\/\/www.linkedin.com\/in\/franciscofelinto\/\"],\"url\":\"https:\/\/nfe.io\/blog\/author\/francisco\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quais s\u00e3o os impostos para MEIs e profissionais liberais? - NFE.io Blog","description":"Neste artigo voc\u00ea vai aprender sobre os principais impostos e obriga\u00e7\u00f5es do MEI e dos profissionais liberais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/","og_locale":"en_US","og_type":"article","og_title":"Quais s\u00e3o os impostos para MEIs e profissionais liberais? - NFE.io Blog","og_description":"Neste artigo voc\u00ea vai aprender sobre os principais impostos e obriga\u00e7\u00f5es do MEI e dos profissionais liberais.","og_url":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/","og_site_name":"NFE.io Blog","article_publisher":"https:\/\/www.facebook.com\/nfe.io","article_author":"https:\/\/www.facebook.com\/francisco.j.felinto\/","article_published_time":"2024-06-20T15:06:34+00:00","article_modified_time":"2024-06-21T12:29:58+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/quais-sao-os-impostos-para-meis-e-profissionais-liberais.jpg","type":"image\/jpeg"}],"author":"Francisco Felinto","twitter_card":"summary_large_image","twitter_creator":"@nfe_io","twitter_site":"@nfe_io","twitter_misc":{"Written by":"Francisco Felinto","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#article","isPartOf":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/"},"author":{"name":"Francisco Felinto","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/2eaaaa06c00fec05b47e7003dae7ed65"},"headline":"Quais s\u00e3o os impostos para MEIs e profissionais liberais?","datePublished":"2024-06-20T15:06:34+00:00","dateModified":"2024-06-21T12:29:58+00:00","mainEntityOfPage":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/"},"wordCount":1237,"commentCount":0,"publisher":{"@id":"https:\/\/nfe.io\/blog\/#organization"},"image":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#primaryimage"},"thumbnailUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/quais-sao-os-impostos-para-meis-e-profissionais-liberais.jpg","articleSection":["Gest\u00e3o Financeira"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/","url":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/","name":"Quais s\u00e3o os impostos para MEIs e profissionais liberais? - NFE.io Blog","isPartOf":{"@id":"https:\/\/nfe.io\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#primaryimage"},"image":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#primaryimage"},"thumbnailUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/quais-sao-os-impostos-para-meis-e-profissionais-liberais.jpg","datePublished":"2024-06-20T15:06:34+00:00","dateModified":"2024-06-21T12:29:58+00:00","description":"Neste artigo voc\u00ea vai aprender sobre os principais impostos e obriga\u00e7\u00f5es do MEI e dos profissionais liberais.","breadcrumb":{"@id":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#primaryimage","url":"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/quais-sao-os-impostos-para-meis-e-profissionais-liberais.jpg","contentUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/quais-sao-os-impostos-para-meis-e-profissionais-liberais.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/nfe.io\/blog\/financeiro\/impostos-mei-profissionais-liberais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nfe.io\/blog\/"},{"@type":"ListItem","position":2,"name":"Quais s\u00e3o os impostos para MEIs e profissionais liberais?"}]},{"@type":"WebSite","@id":"https:\/\/nfe.io\/blog\/#website","url":"https:\/\/nfe.io\/blog\/","name":"NFE.io Blog","description":"Automatize Suas Obriga\u00e7\u00f5es Fiscais com Efici\u00eancia","publisher":{"@id":"https:\/\/nfe.io\/blog\/#organization"},"alternateName":"NFE.io","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nfe.io\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nfe.io\/blog\/#organization","name":"NFE io","alternateName":"NFE","url":"https:\/\/nfe.io\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png","contentUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png","width":143,"height":41,"caption":"NFE io"},"image":{"@id":"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nfe.io","https:\/\/x.com\/nfe_io","https:\/\/github.com\/nfe","https:\/\/www.linkedin.com\/company\/10407705\/","https:\/\/www.youtube.com\/channel\/UCB1PFw8rxeIN64k_t5FWEAQ","https:\/\/www.instagram.com\/nfe.io\/"]},{"@type":"Person","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/2eaaaa06c00fec05b47e7003dae7ed65","name":"Francisco Felinto","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/be0f81adb0794281ac9b3ffc87137ad2bf518c3d8bc98e1fbc6526bfc850433d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be0f81adb0794281ac9b3ffc87137ad2bf518c3d8bc98e1fbc6526bfc850433d?s=96&r=g","caption":"Francisco Felinto"},"description":"S\u00f3cio e CECO - Chief Ecosystem Officer na NFE.io, Mestre em Tecnologia da Informa\u00e7\u00e3o Aplicada, MBI em Gest\u00e3o da Informa\u00e7\u00e3o e Especializa\u00e7\u00e3o em Gest\u00e3o de Projeto integrado ao PMI. Professor Universit\u00e1rio e Ex Diretor da Fatec Osasco (2018-22). Fundador do programa Descodificadas, vice-presidente do Instituto Arte das Na\u00e7\u00f5es e Atuante na UWC - Brasil.","sameAs":["https:\/\/www.facebook.com\/francisco.j.felinto\/","https:\/\/www.instagram.com\/francisco.felinto.jr\/","https:\/\/www.linkedin.com\/in\/franciscofelinto\/"],"url":"https:\/\/nfe.io\/blog\/author\/francisco\/"}]}},"_links":{"self":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts\/12279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/comments?post=12279"}],"version-history":[{"count":0,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts\/12279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/media\/12280"}],"wp:attachment":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/media?parent=12279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/categories?post=12279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/tags?post=12279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}