{"id":12100,"date":"2024-07-20T09:51:31","date_gmt":"2024-07-20T12:51:31","guid":{"rendered":"https:\/\/nfe.io\/blog\/?p=12100"},"modified":"2024-07-22T14:33:15","modified_gmt":"2024-07-22T17:33:15","slug":"servico-sem-nota-fiscal-risco","status":"publish","type":"post","link":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/","title":{"rendered":"Caixa 2: por que prestar servi\u00e7o sem nota fiscal \u00e9 um risco?"},"content":{"rendered":"<p><span class=\"ql-font-huge\">Voc\u00ea j\u00e1 deve ter ouvido falar na express\u00e3o\u00a0<\/span>Caixa 2<span class=\"ql-font-huge\">\u00a0e no fato dessa conduta ser um crime, certo? <\/span><\/p>\n<p><span class=\"ql-font-huge\">O termo\u00a0<\/span>Caixa 2<span class=\"ql-font-huge\">\u00a0quer dizer caixa paralelo, e, na pr\u00e1tica, significa n\u00e3o contabilizar as entradas de dinheiro do seu\u00a0<\/span>fluxo de caixa<span class=\"ql-font-huge\">\u00a0para evitar o pagamento de impostos. <\/span><\/p>\n<p><span class=\"ql-font-huge\">Geralmente, isso est\u00e1 ligado a atividades ilegais. Mas, mesmo quando um servi\u00e7o legal \u00e9 comercializado sem\u00a0<\/span>nota fiscal<span class=\"ql-font-huge\">, ele pode se enquadrar no erro.<\/span><\/p>\n<p><span class=\"ql-font-huge\">Isso acontece porque, ao contr\u00e1rio do que muita gente pensa, n\u00e3o \u00e9 s\u00f3 a venda de produtos que precisa de\u00a0<\/span><strong>nota fiscal<\/strong><span class=\"ql-font-huge\">\u00a0\u2013 presta\u00e7\u00e3o de servi\u00e7os tamb\u00e9m.\u00a0<\/span><\/p>\n<p><span class=\"ql-font-huge\">E os riscos que a empresa corre se n\u00e3o prestar contas ao Fisco adequadamente s\u00e3o grandes. <\/span><\/p>\n<p><span class=\"ql-font-huge\">Quer entender quais os riscos de fazer\u00a0<\/span>caixa 2<span class=\"ql-font-huge\">\u00a0e como evit\u00e1-los fazendo o que \u00e9 certo? Acompanhe!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong class=\"ql-font-huge\">Quem precisa emitir nota fiscal?<\/strong><\/h3>\n<p><span class=\"ql-font-huge\">Da grande corpora\u00e7\u00e3o \u00e0 pequena panificadora do bairro, qualquer\u00a0<\/span>micro,\u00a0pequena,\u00a0m\u00e9dia\u00a0e\u00a0grande\u00a0empresa\u00a0deve emitir\u00a0nota fiscal\u00a0<span class=\"ql-font-huge\">dos produtos ou servi\u00e7os comercializados. <\/span><\/p>\n<p><span class=\"ql-font-huge\">Para\u00a0<\/span>microempreendedores individuais<span class=\"ql-font-huge\">, a regra \u00e9 um pouco diferente: quem vende produto ou presta servi\u00e7o para outra pessoa f\u00edsica, n\u00e3o \u00e9 obrigado a\u00a0<\/span>emitir NF<span class=\"ql-font-huge\">. No entanto, ao negociar com outra pessoa jur\u00eddica, o\u00a0<\/span>MEI<span class=\"ql-font-huge\">\u00a0precisa emitir a\u00a0<\/span>nota fiscal<span class=\"ql-font-huge\">\u00a0tamb\u00e9m.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong class=\"ql-font-huge\">Por que a nota fiscal \u00e9 importante?<\/strong><\/h3>\n<p><span class=\"ql-font-huge\">A\u00a0<\/span>nota fiscal<span class=\"ql-font-huge\">\u00a0\u00e9 uma forma de fazer o\u00a0<\/span>controle de vendas<span class=\"ql-font-huge\">\u00a0realizadas no pa\u00eds. Assim, o governo sabe quanto dinheiro est\u00e1 circulando e qual a porcentagem que deve ir para os cofres p\u00fablicos por meio dos\u00a0<\/span>impostos<span class=\"ql-font-huge\">. <\/span><\/p>\n<p><span class=\"ql-font-huge\">Consequentemente, esse dinheiro deve ser aplicado nos servi\u00e7os prestados pelo Estado para toda a popula\u00e7\u00e3o: seguran\u00e7a, educa\u00e7\u00e3o, sa\u00fade, assist\u00eancia social, etc.<\/span><\/p>\n<p><span class=\"ql-font-huge\">Quando um empreendedor deixa de emitir\u00a0<\/span>nota fiscal<span class=\"ql-font-huge\">, inclusive a de servi\u00e7o, ele pode se enquadrar no crime de\u00a0<\/span>Caixa 2<span class=\"ql-font-huge\">, ou outros v\u00e1rios apontados na lei tribut\u00e1ria. <\/span><\/p>\n<p><span class=\"ql-font-huge\">Todos est\u00e3o ligados \u00e0 famosa sonega\u00e7\u00e3o de imposto, ou seja, \u00e0 falta de pagamento dos tributos devidos.\u00a0<\/span><\/p>\n<p><span class=\"ql-font-huge\">E, apesar da tributa\u00e7\u00e3o do Brasil ser bastante alta, ela serve para manter os recursos p\u00fablicos que abrangem o territ\u00f3rio nacional. <\/span><\/p>\n<p><span class=\"ql-font-huge\">Ao sonegar esse valor, al\u00e9m das chances de ser punido criminalmente, contribui-se para a cultura da corrup\u00e7\u00e3o.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong class=\"ql-font-huge\">Quais riscos a empresa corre se n\u00e3o emitir nota fiscal?<\/strong><\/h3>\n<p><span class=\"ql-font-huge\">O primeiro risco que uma empresa corre quando n\u00e3o\u00a0<\/span><span class=\"ql-font-huge\">emite a NF<\/span><span class=\"ql-font-huge\">, \u00e9 perder clientes. <\/span><\/p>\n<p><span class=\"ql-font-huge\">O consumidor est\u00e1 cada vez mais atento aos seus direitos, inclusive ao de receber a nota, e o fornecedor que se recusa a fazer essa emiss\u00e3o pode perder a venda.<\/span><\/p>\n<p><span class=\"ql-font-huge\">Isso sem contar que a clientela reconhece aquele com\u00e9rcio que, de prop\u00f3sito, n\u00e3o d\u00e1 a\u00a0<\/span>nota fiscal<span class=\"ql-font-huge\">\u00a0para n\u00e3o contabilizar poss\u00edveis impostos. <\/span><\/p>\n<p><span class=\"ql-font-huge\">Sem d\u00favidas, essa \u00e9 uma p\u00e9ssima impress\u00e3o que qualquer marca poderia deixar, n\u00e9? Ent\u00e3o, nada melhor do que ficar bem longe desse tipo de conduta!<\/span><\/p>\n<p><span class=\"ql-font-huge\">Outro fator de risco \u00e9 a puni\u00e7\u00e3o pelo crime. Isso porque, deixar de emitir\u00a0<\/span>nota fiscal<span class=\"ql-font-huge\">\u00a0\u00e9 uma forma de n\u00e3o prestar contas ao Fisco e faltar com os impostos. <\/span><\/p>\n<p><span class=\"ql-font-huge\">Os \u00f3rg\u00e3os do Estado respons\u00e1veis por esse tipo de investiga\u00e7\u00e3o est\u00e3o cada vez mais atentos \u00e0queles que cometem o delito, e as penas podem ser de reclus\u00e3o e multa.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong class=\"ql-font-huge\">Como emitir notas fiscais de servi\u00e7o e controlar impostos?<\/strong><\/h3>\n<p><span class=\"ql-font-huge\">Para emitir\u00a0<\/span>notas fiscais<span class=\"ql-font-huge\">\u00a0de servi\u00e7o, voc\u00ea pode utilizar o processo eletr\u00f4nico ou o manual, que \u00e9 por meio do bloco de papel. <\/span><\/p>\n<p><span class=\"ql-font-huge\">Cada cidade tem a sua pr\u00f3pria legisla\u00e7\u00e3o quanto \u00e0 emiss\u00e3o de\u00a0<\/span>Nota Fiscal de Servi\u00e7o Eletr\u00f4nica<span class=\"ql-font-huge\">, por isso, \u00e9 importante que voc\u00ea consulte o site da prefeitura de onde voc\u00ea mora. <\/span><\/p>\n<p><span class=\"ql-font-huge\">Al\u00e9m disso, um bom caminho para ficar em dia com a emiss\u00e3o de notas e o controle de tributos \u00e9 contar com um\u00a0<\/span>gestor financeiro<span class=\"ql-font-huge\">\u00a0online.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"ql-font-huge\">Aqui na <strong><a href=\"https:\/\/nfe.io\/produtos\/\">NFE.io<\/a><\/strong><\/span><span class=\"ql-font-huge\">, por exemplo, voc\u00ea pode emitir\u00a0<\/span><strong class=\"ql-font-huge\">Notas Fiscais Eletr\u00f4nicas<\/strong><span class=\"ql-font-huge\"> de um jeito r\u00e1pido e f\u00e1cil.\u00a0<\/span><\/p>\n<p>Nosso sistema de emiss\u00e3o de nota fiscal automatiza tarefas chatas e ainda te ajuda a ganhar performance, tempo e dinheiro. Assim, voc\u00ea pode focar no seu neg\u00f3cio, e deixar toda burocracia de comunica\u00e7\u00e3o com as prefeituras com a gente. Afinal, somos especialistas em descomplicar.<\/p>\n<p>Quer saber mais? <a href=\"https:\/\/nfe.io\/contato\/\">Fale com um dos nossos especialistas<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea j\u00e1 deve ter ouvido falar na express\u00e3o\u00a0Caixa 2\u00a0e no fato dessa conduta ser um crime, certo? O termo\u00a0Caixa 2\u00a0quer dizer caixa paralelo,&#8230;<\/p>\n","protected":false},"author":23,"featured_media":12101,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-12100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nota-fiscal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Caixa 2: por que prestar servi\u00e7o sem nota fiscal \u00e9 um risco? - NFE.io Blog<\/title>\n<meta name=\"description\" content=\"Prestar servi\u00e7o sem nota fiscal, tamb\u00e9m conhecido como Caixa 2, \u00e9 um grande risco para o seu neg\u00f3cio. Entenda por que em nosso artigo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caixa 2: por que prestar servi\u00e7o sem nota fiscal \u00e9 um risco? - NFE.io Blog\" \/>\n<meta property=\"og:description\" content=\"Prestar servi\u00e7o sem nota fiscal, tamb\u00e9m conhecido como Caixa 2, \u00e9 um grande risco para o seu neg\u00f3cio. Entenda por que em nosso artigo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/\" \/>\n<meta property=\"og:site_name\" content=\"NFE.io Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nfe.io\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/francisco.j.felinto\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-20T12:51:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T17:33:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/prestar-servico-sem-nota.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco Felinto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nfe_io\" \/>\n<meta name=\"twitter:site\" content=\"@nfe_io\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Felinto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/\"},\"author\":{\"name\":\"Francisco Felinto\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/13cbdfb2ce15a806dcd3c2fffa2cf921\"},\"headline\":\"Caixa 2: por que prestar servi\u00e7o sem nota fiscal \u00e9 um risco?\",\"datePublished\":\"2024-07-20T12:51:31+00:00\",\"dateModified\":\"2024-07-22T17:33:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/\"},\"wordCount\":739,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nfe.io\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/prestar-servico-sem-nota.jpg\",\"articleSection\":[\"Nota Fiscal\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/\",\"url\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/\",\"name\":\"Caixa 2: por que prestar servi\u00e7o sem nota fiscal \u00e9 um risco? - NFE.io Blog\",\"isPartOf\":{\"@id\":\"https:\/\/nfe.io\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/prestar-servico-sem-nota.jpg\",\"datePublished\":\"2024-07-20T12:51:31+00:00\",\"dateModified\":\"2024-07-22T17:33:15+00:00\",\"description\":\"Prestar servi\u00e7o sem nota fiscal, tamb\u00e9m conhecido como Caixa 2, \u00e9 um grande risco para o seu neg\u00f3cio. Entenda por que em nosso artigo.\",\"breadcrumb\":{\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#primaryimage\",\"url\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/prestar-servico-sem-nota.jpg\",\"contentUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/prestar-servico-sem-nota.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nfe.io\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caixa 2: por que prestar servi\u00e7o sem nota fiscal \u00e9 um risco?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nfe.io\/blog\/#website\",\"url\":\"https:\/\/nfe.io\/blog\/\",\"name\":\"NFE.io Blog\",\"description\":\"Automatize Suas Obriga\u00e7\u00f5es Fiscais com Efici\u00eancia\",\"publisher\":{\"@id\":\"https:\/\/nfe.io\/blog\/#organization\"},\"alternateName\":\"NFE.io\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nfe.io\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nfe.io\/blog\/#organization\",\"name\":\"NFE io\",\"alternateName\":\"NFE\",\"url\":\"https:\/\/nfe.io\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png\",\"contentUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png\",\"width\":143,\"height\":41,\"caption\":\"NFE io\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nfe.io\",\"https:\/\/x.com\/nfe_io\",\"https:\/\/github.com\/nfe\",\"https:\/\/www.linkedin.com\/company\/10407705\/\",\"https:\/\/www.youtube.com\/channel\/UCB1PFw8rxeIN64k_t5FWEAQ\",\"https:\/\/www.instagram.com\/nfe.io\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/13cbdfb2ce15a806dcd3c2fffa2cf921\",\"name\":\"Francisco Felinto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/be0f81adb0794281ac9b3ffc87137ad2bf518c3d8bc98e1fbc6526bfc850433d?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/be0f81adb0794281ac9b3ffc87137ad2bf518c3d8bc98e1fbc6526bfc850433d?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Francisco Felinto\"},\"description\":\"S\u00f3cio e CLO - Chief Learning Officer na NFE.io, Mestre em Tecnologia da Informa\u00e7\u00e3o Aplicada, MBI em Gest\u00e3o da Informa\u00e7\u00e3o e Especializa\u00e7\u00e3o em Gest\u00e3o de Projeto integrado ao PMI. Ex Diretor da Fatec Osasco (2018-22), Serasa Experian, Elo Group com projetos na B3, Alelo, Aes Eletropaulo. Fundador das Descodificadas e vice-presidente do Instituto Arte das Na\u00e7\u00f5es.\",\"sameAs\":[\"https:\/\/www.facebook.com\/francisco.j.felinto\/\",\"https:\/\/www.instagram.com\/francisco.felinto.jr\/\",\"https:\/\/www.linkedin.com\/in\/franciscofelinto\/\"],\"url\":\"https:\/\/nfe.io\/blog\/author\/francisco\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caixa 2: por que prestar servi\u00e7o sem nota fiscal \u00e9 um risco? - NFE.io Blog","description":"Prestar servi\u00e7o sem nota fiscal, tamb\u00e9m conhecido como Caixa 2, \u00e9 um grande risco para o seu neg\u00f3cio. Entenda por que em nosso artigo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/","og_locale":"en_US","og_type":"article","og_title":"Caixa 2: por que prestar servi\u00e7o sem nota fiscal \u00e9 um risco? - NFE.io Blog","og_description":"Prestar servi\u00e7o sem nota fiscal, tamb\u00e9m conhecido como Caixa 2, \u00e9 um grande risco para o seu neg\u00f3cio. Entenda por que em nosso artigo.","og_url":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/","og_site_name":"NFE.io Blog","article_publisher":"https:\/\/www.facebook.com\/nfe.io","article_author":"https:\/\/www.facebook.com\/francisco.j.felinto\/","article_published_time":"2024-07-20T12:51:31+00:00","article_modified_time":"2024-07-22T17:33:15+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/prestar-servico-sem-nota.jpg","type":"image\/jpeg"}],"author":"Francisco Felinto","twitter_card":"summary_large_image","twitter_creator":"@nfe_io","twitter_site":"@nfe_io","twitter_misc":{"Written by":"Francisco Felinto","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#article","isPartOf":{"@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/"},"author":{"name":"Francisco Felinto","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/13cbdfb2ce15a806dcd3c2fffa2cf921"},"headline":"Caixa 2: por que prestar servi\u00e7o sem nota fiscal \u00e9 um risco?","datePublished":"2024-07-20T12:51:31+00:00","dateModified":"2024-07-22T17:33:15+00:00","mainEntityOfPage":{"@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/"},"wordCount":739,"commentCount":0,"publisher":{"@id":"https:\/\/nfe.io\/blog\/#organization"},"image":{"@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#primaryimage"},"thumbnailUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/prestar-servico-sem-nota.jpg","articleSection":["Nota Fiscal"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/","url":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/","name":"Caixa 2: por que prestar servi\u00e7o sem nota fiscal \u00e9 um risco? - NFE.io Blog","isPartOf":{"@id":"https:\/\/nfe.io\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#primaryimage"},"image":{"@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#primaryimage"},"thumbnailUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/prestar-servico-sem-nota.jpg","datePublished":"2024-07-20T12:51:31+00:00","dateModified":"2024-07-22T17:33:15+00:00","description":"Prestar servi\u00e7o sem nota fiscal, tamb\u00e9m conhecido como Caixa 2, \u00e9 um grande risco para o seu neg\u00f3cio. Entenda por que em nosso artigo.","breadcrumb":{"@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#primaryimage","url":"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/prestar-servico-sem-nota.jpg","contentUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2024\/06\/prestar-servico-sem-nota.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/servico-sem-nota-fiscal-risco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nfe.io\/blog\/"},{"@type":"ListItem","position":2,"name":"Caixa 2: por que prestar servi\u00e7o sem nota fiscal \u00e9 um risco?"}]},{"@type":"WebSite","@id":"https:\/\/nfe.io\/blog\/#website","url":"https:\/\/nfe.io\/blog\/","name":"NFE.io Blog","description":"Automatize Suas Obriga\u00e7\u00f5es Fiscais com Efici\u00eancia","publisher":{"@id":"https:\/\/nfe.io\/blog\/#organization"},"alternateName":"NFE.io","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nfe.io\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nfe.io\/blog\/#organization","name":"NFE io","alternateName":"NFE","url":"https:\/\/nfe.io\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png","contentUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png","width":143,"height":41,"caption":"NFE io"},"image":{"@id":"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nfe.io","https:\/\/x.com\/nfe_io","https:\/\/github.com\/nfe","https:\/\/www.linkedin.com\/company\/10407705\/","https:\/\/www.youtube.com\/channel\/UCB1PFw8rxeIN64k_t5FWEAQ","https:\/\/www.instagram.com\/nfe.io\/"]},{"@type":"Person","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/13cbdfb2ce15a806dcd3c2fffa2cf921","name":"Francisco Felinto","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/be0f81adb0794281ac9b3ffc87137ad2bf518c3d8bc98e1fbc6526bfc850433d?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be0f81adb0794281ac9b3ffc87137ad2bf518c3d8bc98e1fbc6526bfc850433d?s=96&d=wp_user_avatar&r=g","caption":"Francisco Felinto"},"description":"S\u00f3cio e CLO - Chief Learning Officer na NFE.io, Mestre em Tecnologia da Informa\u00e7\u00e3o Aplicada, MBI em Gest\u00e3o da Informa\u00e7\u00e3o e Especializa\u00e7\u00e3o em Gest\u00e3o de Projeto integrado ao PMI. Ex Diretor da Fatec Osasco (2018-22), Serasa Experian, Elo Group com projetos na B3, Alelo, Aes Eletropaulo. Fundador das Descodificadas e vice-presidente do Instituto Arte das Na\u00e7\u00f5es.","sameAs":["https:\/\/www.facebook.com\/francisco.j.felinto\/","https:\/\/www.instagram.com\/francisco.felinto.jr\/","https:\/\/www.linkedin.com\/in\/franciscofelinto\/"],"url":"https:\/\/nfe.io\/blog\/author\/francisco\/"}]}},"_links":{"self":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts\/12100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/comments?post=12100"}],"version-history":[{"count":0,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts\/12100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/media\/12101"}],"wp:attachment":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/media?parent=12100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/categories?post=12100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/tags?post=12100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}