{"id":11129,"date":"2022-11-16T07:00:15","date_gmt":"2022-11-16T09:00:15","guid":{"rendered":"https:\/\/nfe.io\/blog\/?p=11129"},"modified":"2022-11-16T11:46:41","modified_gmt":"2022-11-16T13:46:41","slug":"damdfe","status":"publish","type":"post","link":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/","title":{"rendered":"DAMDFe: o que \u00e9, como funciona e qual sua import\u00e2ncia?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">O DAMDFe &#8211; Documento Auxiliar do Manifesto Eletr\u00f4nico de Documentos Fiscais \u2013 \u00e9 um documento que cont\u00e9m informa\u00e7\u00f5es necess\u00e1rias para realizar servi\u00e7os de transporte nacional. Assim como outros pap\u00e9is, ele deve ser fornecido pelos prestadores de servi\u00e7o em todas suas atividades.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nesse sentido, ainda h\u00e1 muitos empres\u00e1rios que partilham d\u00favidas sobre a import\u00e2ncia desse item e se faz necess\u00e1rio entend\u00ea-lo. O documento serve para comprovar os servi\u00e7os\u00a0 com transporte de produtos no territ\u00f3rio nacional. Sendo apresentado tamb\u00e9m para os fins de fiscaliza\u00e7\u00e3o.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ou seja, a emiss\u00e3o do mesmo evita que uma empresa tenha problemas fiscais. Dito isso, confira a seguir qual a import\u00e2ncia do DAMDFe, como emitir e em quais situa\u00e7\u00f5es deve ser apresentado. Descubra, ainda, como \u00e9 poss\u00edvel otimizar o seu neg\u00f3cio na hora de obter o documento.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">O que \u00e9 o DAMDFe?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Esse documento \u00e9 a vers\u00e3o impressa do <\/span><a href=\"https:\/\/nfe.io\/blog\/nota-fiscal\/manifesto-de-documentos-fiscais-eletronicos\/\"><span style=\"font-weight: 400;\">Manifesto Eletr\u00f4nico dos Documentos Fiscais (MDFe)<\/span><\/a><span style=\"font-weight: 400;\">. O DAMDFe ajuda a identificar as cargas transportadas e os conte\u00fados das mercadorias de forma a assegurar o servi\u00e7o.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Deste modo, o item serve para comprovar os conte\u00fados em eventuais situa\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e de acompanhamento dos trajetos. Consequentemente, permite que as cargas cheguem, sem problemas, aos destinos.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Para que serve esse documento?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">O principal objetivo do DAMDFe \u00e9 facilitar a verifica\u00e7\u00e3o das mercadorias transportadas, isso porque ele funciona como uma vers\u00e3o impressa ligada \u00e0 MDFe. Portanto, na fiscaliza\u00e7\u00e3o basta solicit\u00e1-lo e atrav\u00e9s dele consultar o Manifesto Eletr\u00f4nico no sistema.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Basicamente, todo DAMDFe vem acompanhado por um MDFe correspondente. Por exemplo, em um servi\u00e7o de frete feito do munic\u00edpio A para o C, ser\u00e1 necess\u00e1ria a emiss\u00e3o de um \u00fanico MDFe, portanto, um \u00fanico DAMDFe.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas, se durante esse transporte for necess\u00e1rio realizar uma entrega no ponto B, ser\u00e3o necess\u00e1rios dois Manifestos Eletr\u00f4nicos. Eles correspondem ao transporte A \u2014 B e B \u2014 C, onde todos eles devem ser acompanhados por seus respectivos documentos auxiliares.<\/span><\/p>\n<p><b>Veja tamb\u00e9m:<\/b> <a href=\"https:\/\/nfe.io\/blog\/nota-fiscal\/consultar-nota-fiscal-emitida-para-meu-cnpj\/\"><span style=\"font-weight: 400;\">Como consultar as notas fiscais emitidas contra o seu CNPJ<\/span><\/a><\/p>\n<h2><span style=\"font-weight: 400;\">Diferen\u00e7a entre DAMDFe e MDFe<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">O Manifesto Eletr\u00f4nico de Documentos Fiscais \u2013\u00a0 MDFe \u2013 \u00e9 o agrupamento dos documentos de Conhecimentos de Transporte (CTe) de forma online. O DAMDFe \u00e9 a vers\u00e3o impressa e complementar ao MDFe e juntos eles facilitam a fiscaliza\u00e7\u00e3o do transporte de cargas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As informa\u00e7\u00f5es de emitente, destinat\u00e1rio, valores de frete e mercadoria devem estar contidas no CTe, esse deve ser emitido individualmente para cada mercadoria. Por outro lado, o MDF-e e o DAMDFe acompanham a carga em cada frete.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Quem deve emitir DAMDFe?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">As empresas que transportam as suas cargas por conta pr\u00f3pria ou os servi\u00e7os terceirizados de entregas, devem emitir o documento. No entanto, se uma carga \u00e9 transportada sem essas informa\u00e7\u00f5es, poder\u00e1 prever multa \u00e0 empresa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, a emiss\u00e3o do DAMDFe tornou- se obrigat\u00f3ria desde 2020. Portanto, todos os empreendimentos que realizam os transportes de cargas devem se enquadrar \u00e0s regras previstas na lei federal.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Como imprimir o DAMDFe?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">O DAMDFe pode ser impresso diretamente pela Secretaria de Fazenda (SEFAZ), na mesma forma de emiss\u00e3o do Manifesto de Documentos. Esse servi\u00e7o facilita o dia a dia de transportes j\u00e1 que n\u00e3o \u00e9 necess\u00e1rio a contrata\u00e7\u00e3o de sistemas terceirizados.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dessa forma, o documento pode ser impresso logo ap\u00f3s que o MDFe \u00e9 autorizado. E para facilitar a emiss\u00e3o, a plataforma \u00e9 online e voc\u00ea pode optar por utilizar a vers\u00e3o PDF que fica na nuvem para enviar ao cliente, ou acompanhar a carga a fim de evitar poss\u00edveis imprevistos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mesmo assim, caso ocorra algum extravio e for necess\u00e1rio reimprimir o documento, tamb\u00e9m \u00e9 poss\u00edvel. Basta acessar o sistema emissor do Manifesto Eletr\u00f4nico e procurar pelo arquivo em PDF ou XML.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Import\u00e2ncia do DAMDFe<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Com o DAMDFe, o processo de fiscaliza\u00e7\u00e3o sobre as mercadorias transportadas torna- se mais f\u00e1cil e \u00e1gil. Al\u00e9m disso, a fiscaliza\u00e7\u00e3o pode acessar as informa\u00e7\u00f5es pelo manifesto eletr\u00f4nico do sistema.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por\u00e9m, o DAMDFe deve ser emitido conforme algumas regras para o transporte das mercadorias. Ou seja, poder\u00e1 ser necess\u00e1rio a apresenta\u00e7\u00e3o de mais de um documento na seguinte ocasi\u00e3o:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">entrega do munic\u00edpio A para o C: um manifesto;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">transporte do A para o B antes do C: dois documentos.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Sendo assim, a import\u00e2ncia do DAMDFe deve ser analisada sempre que uma viagem for realizada entre um ou mais munic\u00edpios. Todavia, a empresa deve consultar as regras para o caso de viagens para fora do seu estado.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso \u00e9 importante que a organiza\u00e7\u00e3o das entregas esteja em dia, principalmente quando se trata das informa\u00e7\u00f5es do DAMDFe. Para evitar problemas com a fiscaliza\u00e7\u00e3o \u00e9 preciso de uma <\/span><a href=\"https:\/\/nfe.io\/blog\/gestao-empresarial\/o-que-e-gestao-documentos\/\"><span style=\"font-weight: 400;\">gest\u00e3o de documentos<\/span><\/a><span style=\"font-weight: 400;\"> eficiente e \u00e1gil com <\/span><a href=\"https:\/\/pluga.co\/blog\/automatizar-processos\/\"><span style=\"font-weight: 400;\">processos automatizados<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m de tudo, o documento contribui para que todos os tributos sejam recolhidos e evita, ainda, a possibilidade de risco com as mercadorias. Sendo assim, \u00e9 imprescind\u00edvel que a <\/span><a href=\"https:\/\/nfe.io\/blog\/financeiro\/o-que-e-gestao-fiscal\/\"><span style=\"font-weight: 400;\">gest\u00e3o fiscal<\/span><\/a><span style=\"font-weight: 400;\"> da sua empresa forne\u00e7a com seguran\u00e7a os servi\u00e7os prestados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E se deseja saber mais sobre o departamento fiscal e como conduzi-lo com efic\u00e1cia, confira esse artigo que separamos: <\/span><a href=\"https:\/\/nfe.io\/blog\/financeiro\/tudo-sobre-departamento-fiscal\/\"><span style=\"font-weight: 400;\">Tudo sobre departamento fiscal e confira 5 dicas para melhorar sua gest\u00e3o<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O DAMDFe &#8211; Documento Auxiliar do Manifesto Eletr\u00f4nico de Documentos Fiscais \u2013 \u00e9 um documento que cont\u00e9m informa\u00e7\u00f5es necess\u00e1rias para realizar servi\u00e7os de&#8230;<\/p>\n","protected":false},"author":23,"featured_media":11130,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-11129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nota-fiscal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O que e\u0301 DAMDFe e como ela funciona?<\/title>\n<meta name=\"description\" content=\"O DAMDFe deve ser emitido para que as mercadorias n\u00e3o arrisquem serem apreendidas com a fiscaliza\u00e7\u00e3o. Entenda como emitir!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que e\u0301 DAMDFe e como ela funciona?\" \/>\n<meta property=\"og:description\" content=\"O DAMDFe deve ser emitido para que as mercadorias n\u00e3o arrisquem serem apreendidas com a fiscaliza\u00e7\u00e3o. Entenda como emitir!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/\" \/>\n<meta property=\"og:site_name\" content=\"NFE.io Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nfe.io\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/francisco.j.felinto\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-16T09:00:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-16T13:46:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nfe.io\/blog\/app\/uploads\/2022\/11\/DAMDFe.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Francisco Felinto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nfe_io\" \/>\n<meta name=\"twitter:site\" content=\"@nfe_io\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco Felinto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/\"},\"author\":{\"name\":\"Francisco Felinto\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/13cbdfb2ce15a806dcd3c2fffa2cf921\"},\"headline\":\"DAMDFe: o que \u00e9, como funciona e qual sua import\u00e2ncia?\",\"datePublished\":\"2022-11-16T09:00:15+00:00\",\"dateModified\":\"2022-11-16T13:46:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/\"},\"wordCount\":910,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/nfe.io\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2022\/11\/DAMDFe.png\",\"articleSection\":[\"Nota Fiscal\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/\",\"url\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/\",\"name\":\"O que e\u0301 DAMDFe e como ela funciona?\",\"isPartOf\":{\"@id\":\"https:\/\/nfe.io\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2022\/11\/DAMDFe.png\",\"datePublished\":\"2022-11-16T09:00:15+00:00\",\"dateModified\":\"2022-11-16T13:46:41+00:00\",\"description\":\"O DAMDFe deve ser emitido para que as mercadorias n\u00e3o arrisquem serem apreendidas com a fiscaliza\u00e7\u00e3o. Entenda como emitir!\",\"breadcrumb\":{\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#primaryimage\",\"url\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2022\/11\/DAMDFe.png\",\"contentUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2022\/11\/DAMDFe.png\",\"width\":800,\"height\":500,\"caption\":\"O que \u00e9 DAMDFe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nfe.io\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAMDFe: o que \u00e9, como funciona e qual sua import\u00e2ncia?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nfe.io\/blog\/#website\",\"url\":\"https:\/\/nfe.io\/blog\/\",\"name\":\"NFE.io Blog\",\"description\":\"Automatize Suas Obriga\u00e7\u00f5es Fiscais com Efici\u00eancia\",\"publisher\":{\"@id\":\"https:\/\/nfe.io\/blog\/#organization\"},\"alternateName\":\"NFE.io\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nfe.io\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nfe.io\/blog\/#organization\",\"name\":\"NFE io\",\"alternateName\":\"NFE\",\"url\":\"https:\/\/nfe.io\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png\",\"contentUrl\":\"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png\",\"width\":143,\"height\":41,\"caption\":\"NFE io\"},\"image\":{\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/nfe.io\",\"https:\/\/x.com\/nfe_io\",\"https:\/\/github.com\/nfe\",\"https:\/\/www.linkedin.com\/company\/10407705\/\",\"https:\/\/www.youtube.com\/channel\/UCB1PFw8rxeIN64k_t5FWEAQ\",\"https:\/\/www.instagram.com\/nfe.io\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/13cbdfb2ce15a806dcd3c2fffa2cf921\",\"name\":\"Francisco Felinto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nfe.io\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/be0f81adb0794281ac9b3ffc87137ad2bf518c3d8bc98e1fbc6526bfc850433d?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/be0f81adb0794281ac9b3ffc87137ad2bf518c3d8bc98e1fbc6526bfc850433d?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Francisco Felinto\"},\"description\":\"S\u00f3cio e CLO - Chief Learning Officer na NFE.io, Mestre em Tecnologia da Informa\u00e7\u00e3o Aplicada, MBI em Gest\u00e3o da Informa\u00e7\u00e3o e Especializa\u00e7\u00e3o em Gest\u00e3o de Projeto integrado ao PMI. Ex Diretor da Fatec Osasco (2018-22), Serasa Experian, Elo Group com projetos na B3, Alelo, Aes Eletropaulo. Fundador das Descodificadas e vice-presidente do Instituto Arte das Na\u00e7\u00f5es.\",\"sameAs\":[\"https:\/\/www.facebook.com\/francisco.j.felinto\/\",\"https:\/\/www.instagram.com\/francisco.felinto.jr\/\",\"https:\/\/www.linkedin.com\/in\/franciscofelinto\/\"],\"url\":\"https:\/\/nfe.io\/blog\/author\/francisco\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que e\u0301 DAMDFe e como ela funciona?","description":"O DAMDFe deve ser emitido para que as mercadorias n\u00e3o arrisquem serem apreendidas com a fiscaliza\u00e7\u00e3o. Entenda como emitir!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/","og_locale":"en_US","og_type":"article","og_title":"O que e\u0301 DAMDFe e como ela funciona?","og_description":"O DAMDFe deve ser emitido para que as mercadorias n\u00e3o arrisquem serem apreendidas com a fiscaliza\u00e7\u00e3o. Entenda como emitir!","og_url":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/","og_site_name":"NFE.io Blog","article_publisher":"https:\/\/www.facebook.com\/nfe.io","article_author":"https:\/\/www.facebook.com\/francisco.j.felinto\/","article_published_time":"2022-11-16T09:00:15+00:00","article_modified_time":"2022-11-16T13:46:41+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/nfe.io\/blog\/app\/uploads\/2022\/11\/DAMDFe.png","type":"image\/png"}],"author":"Francisco Felinto","twitter_card":"summary_large_image","twitter_creator":"@nfe_io","twitter_site":"@nfe_io","twitter_misc":{"Written by":"Francisco Felinto","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#article","isPartOf":{"@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/"},"author":{"name":"Francisco Felinto","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/13cbdfb2ce15a806dcd3c2fffa2cf921"},"headline":"DAMDFe: o que \u00e9, como funciona e qual sua import\u00e2ncia?","datePublished":"2022-11-16T09:00:15+00:00","dateModified":"2022-11-16T13:46:41+00:00","mainEntityOfPage":{"@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/"},"wordCount":910,"commentCount":0,"publisher":{"@id":"https:\/\/nfe.io\/blog\/#organization"},"image":{"@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#primaryimage"},"thumbnailUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2022\/11\/DAMDFe.png","articleSection":["Nota Fiscal"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/","url":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/","name":"O que e\u0301 DAMDFe e como ela funciona?","isPartOf":{"@id":"https:\/\/nfe.io\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#primaryimage"},"image":{"@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#primaryimage"},"thumbnailUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2022\/11\/DAMDFe.png","datePublished":"2022-11-16T09:00:15+00:00","dateModified":"2022-11-16T13:46:41+00:00","description":"O DAMDFe deve ser emitido para que as mercadorias n\u00e3o arrisquem serem apreendidas com a fiscaliza\u00e7\u00e3o. Entenda como emitir!","breadcrumb":{"@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#primaryimage","url":"https:\/\/nfe.io\/blog\/app\/uploads\/2022\/11\/DAMDFe.png","contentUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2022\/11\/DAMDFe.png","width":800,"height":500,"caption":"O que \u00e9 DAMDFe"},{"@type":"BreadcrumbList","@id":"https:\/\/nfe.io\/blog\/nota-fiscal\/damdfe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nfe.io\/blog\/"},{"@type":"ListItem","position":2,"name":"DAMDFe: o que \u00e9, como funciona e qual sua import\u00e2ncia?"}]},{"@type":"WebSite","@id":"https:\/\/nfe.io\/blog\/#website","url":"https:\/\/nfe.io\/blog\/","name":"NFE.io Blog","description":"Automatize Suas Obriga\u00e7\u00f5es Fiscais com Efici\u00eancia","publisher":{"@id":"https:\/\/nfe.io\/blog\/#organization"},"alternateName":"NFE.io","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nfe.io\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nfe.io\/blog\/#organization","name":"NFE io","alternateName":"NFE","url":"https:\/\/nfe.io\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png","contentUrl":"https:\/\/nfe.io\/blog\/app\/uploads\/2020\/06\/logofooter.png","width":143,"height":41,"caption":"NFE io"},"image":{"@id":"https:\/\/nfe.io\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nfe.io","https:\/\/x.com\/nfe_io","https:\/\/github.com\/nfe","https:\/\/www.linkedin.com\/company\/10407705\/","https:\/\/www.youtube.com\/channel\/UCB1PFw8rxeIN64k_t5FWEAQ","https:\/\/www.instagram.com\/nfe.io\/"]},{"@type":"Person","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/13cbdfb2ce15a806dcd3c2fffa2cf921","name":"Francisco Felinto","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nfe.io\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/be0f81adb0794281ac9b3ffc87137ad2bf518c3d8bc98e1fbc6526bfc850433d?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be0f81adb0794281ac9b3ffc87137ad2bf518c3d8bc98e1fbc6526bfc850433d?s=96&d=wp_user_avatar&r=g","caption":"Francisco Felinto"},"description":"S\u00f3cio e CLO - Chief Learning Officer na NFE.io, Mestre em Tecnologia da Informa\u00e7\u00e3o Aplicada, MBI em Gest\u00e3o da Informa\u00e7\u00e3o e Especializa\u00e7\u00e3o em Gest\u00e3o de Projeto integrado ao PMI. Ex Diretor da Fatec Osasco (2018-22), Serasa Experian, Elo Group com projetos na B3, Alelo, Aes Eletropaulo. Fundador das Descodificadas e vice-presidente do Instituto Arte das Na\u00e7\u00f5es.","sameAs":["https:\/\/www.facebook.com\/francisco.j.felinto\/","https:\/\/www.instagram.com\/francisco.felinto.jr\/","https:\/\/www.linkedin.com\/in\/franciscofelinto\/"],"url":"https:\/\/nfe.io\/blog\/author\/francisco\/"}]}},"_links":{"self":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts\/11129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/comments?post=11129"}],"version-history":[{"count":0,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/posts\/11129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/media\/11130"}],"wp:attachment":[{"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/media?parent=11129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/categories?post=11129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nfe.io\/blog\/wp-json\/wp\/v2\/tags?post=11129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}